{"id":295,"date":"2011-10-26T14:49:09","date_gmt":"2011-10-26T13:49:09","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/plazadegaraje\/?p=295"},"modified":"2011-10-26T14:49:09","modified_gmt":"2011-10-26T13:49:09","slug":"el-ford-ranger-primer-pick-up-en-conseguir-las-5-estrellas-euroncap","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/2011\/10\/26\/el-ford-ranger-primer-pick-up-en-conseguir-las-5-estrellas-euroncap\/","title":{"rendered":"El Ford Ranger, primer pick up en conseguir las 5 estrellas EuroNcap"},"content":{"rendered":"<p>El consorcio europeo EuroNCAP ha otorgado la m\u00e1xima puntuaci\u00f3n (cinco estrellas) en materia de seguridad al Ford Explorer, que se convierte de esta forma en el primer pick up que consigue esta distinci\u00f3n.<\/p>\n<p>El consorcio europeo encargado de la puntuaci\u00f3n en materia de seguridad ha dado a conocer los \u00faltimos resultados de sus pruebas de choque, en los que adem\u00e1s del Ford Ranger, otros diez modelos consiguen las cinco estrellas. Por su parte, el Lancia Voyager, pese a mejorar su puntuaci\u00f3n, se queda con cuatro estrellas.<\/p>\n<div id=\"attachment_297\" style=\"width: 494px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/blogs.elcorreo.com\/plazadegaraje\/2011\/10\/26\/el-ford-ranger-primer-pick-up-en-conseguir-las-5-estrellas-euroncap\/imgford-ranger1\/\" rel=\"attachment wp-att-297\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-297\" class=\"size-full wp-image-297\" title=\"imgford ranger1\" src=\"\/plazadegaraje\/wp-content\/uploads\/sites\/36\/2011\/10\/imgford-ranger1.jpg\" alt=\"\" width=\"484\" height=\"361\" srcset=\"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-content\/uploads\/sites\/36\/2011\/10\/imgford-ranger1.jpg 484w, https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-content\/uploads\/sites\/36\/2011\/10\/imgford-ranger1-300x224.jpg 300w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/a><p id=\"caption-attachment-297\" class=\"wp-caption-text\">Ford Ranger<\/p><\/div>\n<p>Entre los modelos que consiguen la m\u00e1xima puntuaci\u00f3n destaca el Audi Q3, el primer autom\u00f3vil de la firma de los cuatro aros que se fabrica en las instalaciones de Seat en Martorel.<\/p>\n<p>Adem\u00e1s, tambi\u00e9n logran las cinco estrellas el BMW Serie 1, el Chevrolet Captiva, el Fiat Freemont, Hyundai Veloster, Mercedes Clase M, Opel Astra GTC, Opel Zafira Tourer, Lancia Thema y Toyota Yaris. El Lancia Voyager s\u00f3lo consigue cuatro estrellas.<\/p>\n<p>El secretario general de EuroNCAP, Michiel van Ratingen, destac\u00f3 que la protecci\u00f3n a peatones del Ford Ranger eleva la seguridad de los pick up, que hasta el momento &#8220;no hab\u00edan demostrado ser los veh\u00edculos m\u00e1s seguros&#8221;.<\/p>\n<p>EuroNCAP destaca asimismo que los modelos Lancia Thema, Lancia Voyager y Fiat Feemont son los primeros modelos analizados tras la toma de control de Chrysler por parte de Fiat. Sobre este particular, destaca el progreso del Voyager, con resultados &#8220;prometedores&#8221; pese a obtener cuatro estrellas.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El consorcio europeo EuroNCAP ha otorgado la m\u00e1xima puntuaci\u00f3n (cinco estrellas) en materia de seguridad al Ford Explorer, que se convierte de esta forma en el primer pick up que consigue esta distinci\u00f3n. El consorcio europeo encargado de la puntuaci\u00f3n en materia de seguridad ha dado a conocer los \u00faltimos resultados de sus pruebas de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":51,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-295","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/posts\/295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/comments?post=295"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/posts\/295\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/media?parent=295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/categories?post=295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/tags?post=295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}