{"id":289,"date":"2011-10-20T12:16:59","date_gmt":"2011-10-20T11:16:59","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/plazadegaraje\/?p=289"},"modified":"2011-10-20T12:16:59","modified_gmt":"2011-10-20T11:16:59","slug":"si-los-coches-electricos-son-asi-yo-me-apunto","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/2011\/10\/20\/si-los-coches-electricos-son-asi-yo-me-apunto\/","title":{"rendered":"Si los coches el\u00e9ctricos son as\u00ed, yo me apunto"},"content":{"rendered":"<p>Hasta ahora no ten\u00eda deemasiado aprecio a los coches el\u00e9ctricos, h\u00edbridos y dem\u00e1s alternativas verdes. \u00bfC\u00f3mo quieren compararlos a un V8 a plena potencia? Pero Mercedes, bendita Mercedes, acaba de hacerme cambiar de opini\u00f3n. Con la foto deber\u00eda valernos.<\/p>\n<div id=\"attachment_290\" style=\"width: 590px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/blogs.elcorreo.com\/plazadegaraje\/2011\/10\/20\/si-los-coches-electricos-son-asi-yo-me-apunto\/580mercedes-f-1251\/\" rel=\"attachment wp-att-290\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-290\" class=\"size-full wp-image-290\" title=\"Merdeces 125!\" src=\"\/plazadegaraje\/wp-content\/uploads\/sites\/36\/2011\/10\/580mercedes-f-1251.jpg\" alt=\"\" width=\"580\" height=\"387\" srcset=\"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-content\/uploads\/sites\/36\/2011\/10\/580mercedes-f-1251.jpg 580w, https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-content\/uploads\/sites\/36\/2011\/10\/580mercedes-f-1251-300x200.jpg 300w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/a><p id=\"caption-attachment-290\" class=\"wp-caption-text\">As\u00ed ser\u00e1 el CL en 2025<\/p><\/div>\n<p>Pero es que hay m\u00e1s. El concept F125!, la visi\u00f3n que Mercedes tiene para el CL en 2025, es una peque\u00f1a maravilla t\u00e9cnica. De entrada, su autonom\u00eda es de 1000 kil\u00f3metros. Mil kil\u00f3metros con emisiones cero. Todo gracias a una pila de hidr\u00f3geno.<\/p>\n<p>Y nada de ir despacio. 220 km\/h de velocidad punta en este h\u00edbrido (puede funcionar en modo el\u00e9ctrico durante 50 km gracias a una bater\u00eda de ion-azufre que se carga sin cables) que desarrolla 231 CV. Si no es suficiente para sonreir, atentos. Acelera de 0 a 100 en 4,9 segundos.<br \/>\nEl futuro es verde, Mercedes dixit<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hasta ahora no ten\u00eda deemasiado aprecio a los coches el\u00e9ctricos, h\u00edbridos y dem\u00e1s alternativas verdes. \u00bfC\u00f3mo quieren compararlos a un V8 a plena potencia? Pero Mercedes, bendita Mercedes, acaba de hacerme cambiar de opini\u00f3n. Con la foto deber\u00eda valernos. Pero es que hay m\u00e1s. El concept F125!, la visi\u00f3n que Mercedes tiene para el CL [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":51,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-289","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/posts\/289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/comments?post=289"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/posts\/289\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/media?parent=289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/categories?post=289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/plazadegaraje\/wp-json\/wp\/v2\/tags?post=289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}