{"id":369,"date":"2011-01-26T09:00:00","date_gmt":"2011-01-26T09:00:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/oscarterol\/?p=369"},"modified":"2011-01-26T09:00:00","modified_gmt":"2011-01-26T09:00:00","slug":"leyes","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/oscarterol\/2011\/01\/26\/leyes\/","title":{"rendered":"Leyes"},"content":{"rendered":"<div>Buenos d\u00edas Mari Luz y los dem\u00e1s. La realidad manda y hace que todo sea cambiante, la vida es para quien se la pelea. Un abrazo. Os dejo el art\u00edculo de hoy.<\/div>\n<div>\n<\/div>\n<div>\n<p class=\"MsoNormal\">Leyes<\/p>\n<p class=\"MsoNormal\"><o:p> <\/o:p><\/p>\n<p class=\"MsoNormal\"><<Ayer unos autores espa\u00f1oles que faenaban en el \u00edndice de su libro lograron repeler el ataque de unos piratas juveniles gracias a la aparici\u00f3n, in extremis, de la fragata Sinde. El presidente de la cofrad\u00eda de pescadores, Alex de la Iglesia, dimite de su cargo porque ya no diferencia a los malos de los buenos en sus pel\u00edculas>>. Estas leyes de nuevo cu\u00f1o, como la ley antitabaco y esta que quiere acabar con los p\u00edcaros sucesores del Lazarillo de Tormes v\u00eda ADSL, que se est\u00e1 sacando el gobierno de la manga pastelera nos vienen mejor de lo que pensamos. S\u00ed, ve\u00e1mosle al tema el lado positivo. Cada ley represiva, o prohibitiva que nace genera un grupo de damnificados nuevo; una nueva organizaci\u00f3n social con unos puntos de encuentro evidentes y unos objetivos comunes; un milagro de uni\u00f3n en este sistema que dinamita y separa por norma y por siglas. As\u00ed pues, hoy en d\u00eda, se puede dar el caso de un ciudadano, de Guadalajara, por poner un lugar, votante convencido del PP, hostelero para m\u00e1s se\u00f1as, que est\u00e9 e contra de la ley del tabaco y de la ley Sinde; y que coincida en sus perjuicios y quejas con un votante militante del PSOE de su mismo barrio, hasta el punto de formar una asociaci\u00f3n para organizar las protestas pertinentes. Lo que separa la pol\u00edtica lo une la prohibici\u00f3n. Y si tiramos de la manta de la afinidades comunes, seguramente que estos dos se\u00f1ores son fans de Berlusconi en su papel de buf\u00f3n de Europa. Lo que demuestra que no hay una mente pura ideol\u00f3gicamente hablando, todos tenemos nuestras alcobas ocultas donde duermen los yos inconfesables. Nos resistimos a ser borregos porque dentro de cada uno de nosotros, tambi\u00e9n, vive un pastor con la vara, o un pirata cojo. Hablando de Berlusconi, creo que es una de las decadencias m\u00e1s divertidas que nos ha tocado presenciar. Ha llevado su af\u00e1n de control hasta l\u00edmites insospechados. No nos extra\u00f1e si, en los restaurantes italianos, a partir de ahora, en la carta, hay un aparte con \u201clas sugerencias de Silvio\u201d, y si nos las pides, lo mismo te llama por tel\u00e9fono y te monta el numerito de \u201chola Rafaela\u201d. Pasen buen d\u00eda.<\/p><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Buenos d\u00edas Mari Luz y los dem\u00e1s. La realidad manda y hace que todo sea cambiante, la vida es para quien se la pelea. Un abrazo. Os dejo el art\u00edculo de hoy. Leyes . Estas leyes de nuevo cu\u00f1o, como la ley antitabaco y esta que quiere acabar con los p\u00edcaros sucesores del Lazarillo de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":42,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-369","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/posts\/369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/comments?post=369"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/posts\/369\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/media?parent=369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/categories?post=369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/tags?post=369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}