{"id":350,"date":"2010-09-03T09:21:00","date_gmt":"2010-09-03T09:21:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/oscarterol\/?p=350"},"modified":"2010-09-03T09:21:00","modified_gmt":"2010-09-03T09:21:00","slug":"dios-si-dios-no","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/oscarterol\/2010\/09\/03\/dios-si-dios-no\/","title":{"rendered":"Dios s\u00ed, Dios no&#8230;"},"content":{"rendered":"<p>Buenos d\u00edas hermandad, os saludo con la emoci\u00f3n de un ni\u00f1o enfrent\u00e1ndose al primer d\u00eda de clase. Hoy, contra todo pron\u00f3stico me he levantado de la piltra con la necesidad de colgar palabrer\u00eda en este nuestro blog. No s\u00e9 si estar\u00e9 curado o estoy delirando, el caso es que no me lo voy a mirar porque seguro que me encuentran algo peor.<\/p>\n<p> Dispongo de un ladrillo mensajero que comparto con agrado.<\/p>\n<p> <P style=\"MARGIN: 0cm 0cm 0pt\" class=MsoNormal><B><FONT size=3><FONT face=\"Times New Roman\">Hawking<?xml:namespace prefix = o ns = \"urn:schemas-microsoft-com:office:office\" \/><o:p><\/o:p><\/FONT><\/FONT><\/B><\/p>\n<p> <P style=\"MARGIN: 0cm 0cm 0pt\" class=MsoNormal><o:p><FONT size=3 face=\"Times New Roman\"> <\/FONT><\/o:p><\/p>\n<p> <P style=\"MARGIN: 0cm 0cm 0pt\" class=MsoNormal><FONT size=3 face=\"Times New Roman\">De nombre Stephen, un hombre, f\u00edsico y cosm\u00f3logo para m\u00e1s se\u00f1as, con el que no resultar\u00eda f\u00e1cil tener una discusi\u00f3n sobre lo que ocurre por encima de nuestras cabezas, porque, seg\u00fan parece, lo sabe todo. Hay algunas personas que gozan de la credibilidad general, esas que cuando hablan sientan c\u00e1tedra, en otras palabras: son los que deciden por todos. Este se\u00f1or, s\u00ed, el de la silla de ruedas, es un claro ejemplo. Tambi\u00e9n es cierto que para llevarle la contraria con cierta dignidad hay que estudiar mucho, es mejor discutir de \u201cla Esteban\u201d, o de la nueva crisis del Madrid, temas que est\u00e1n al alcance de cualquier cociente intelectual. Pues eso, que el amigo Stephen, a estas alturas del bel\u00e9n, dice \u2013 en un libro que saldr\u00e1 a la venta en unos d\u00edas- que podemos descartar a Dios como creador del universo. O sea, que la f\u00edsica se basta y se sobra ella solita para pertrechar<SPAN style=\"mso-spacerun: yes\">  <\/SPAN>lo que com\u00fanmente conocemos como \u201cnuestra existencia\u201d. Curiosamente, el mismo se\u00f1or Hawking, en un tratado anterior publicado en la d\u00e9cada de los ochenta, admit\u00eda que no eran incompatibles la fe y las matem\u00e1ticas; Dios pod\u00eda andar perfectamente detr\u00e1s de las calculadoras. A Dios le est\u00e1 ocurriendo lo mismo que a algunos alimentos, como el aceite de oliva por ejemplo, que, dependiendo la moda, es conveniente o no. Ahora, no combina bien con la ciencia y nos lo cargamos. Igual, dentro de unos a\u00f1os, lo tenemos que resucitar para entender la llegada de los primeros extraterrestres, ya lo veremos. Yo, en principio, respeto cualquier opini\u00f3n, porque, pero no nos enga\u00f1emos, la misma fe que nos piden las religiones para comulgar con sus creencias nos la exige la ciencia. Tan incre\u00edble resulta un Dios todopoderoso como que nacemos de una explosi\u00f3n. Pero, y teniendo en cuenta lo que pesan los pasos de la Semana Santa, creo que ser\u00eda conveniente incluirle a Dios en los planes del universo, por si acaso. A ver si le cuadra esta teor\u00eda se\u00f1or Hawking: A Dios le estall\u00f3 el universo en las manos, mientras o manipulaba, y ahora se encuentra en paradero desconocido. As\u00ed todos contentos, que es de lo que se trata. Pasen buen d\u00eda.<\/FONT><\/p>\n<p> Gozar es poco para lo que os merec\u00e9is. Abrazooooo de osooooooooooooooooo<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Buenos d\u00edas hermandad, os saludo con la emoci\u00f3n de un ni\u00f1o enfrent\u00e1ndose al primer d\u00eda de clase. Hoy, contra todo pron\u00f3stico me he levantado de la piltra con la necesidad de colgar palabrer\u00eda en este nuestro blog. No s\u00e9 si estar\u00e9 curado o estoy delirando, el caso es que no me lo voy a mirar [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":42,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-350","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/posts\/350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/comments?post=350"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/posts\/350\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/media?parent=350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/categories?post=350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/tags?post=350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}