{"id":347,"date":"2010-05-21T07:34:00","date_gmt":"2010-05-21T07:34:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/oscarterol\/?p=347"},"modified":"2010-05-21T07:34:00","modified_gmt":"2010-05-21T07:34:00","slug":"poco-poco","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/oscarterol\/2010\/05\/21\/poco-poco\/","title":{"rendered":"Poco a poco"},"content":{"rendered":"<p>Poco a poco; s\u00ed, un corta pega de art\u00edculo con el detalle floral de una fotito, de acuerdo, pero lo importante es asomar. estoy convaleciente de un gran periodo de ausencia, joder, soy vasco y t\u00edmido, ahora no puedo desnudarme a la primera de cambio. Me siento como aquel marido que baj\u00f3 a por tabaco y volvi\u00f3 a los a\u00f1os a conocer a sus nietos. <\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><B><FONT size=3><FONT face=\"Times New Roman\">Especies<?xml:namespace prefix = o ns = \"urn:schemas-microsoft-com:office:office\" \/><o:p><\/o:p><\/FONT><\/FONT><\/B><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><o:p><FONT face=\"Times New Roman\" size=3><\/FONT><\/o:p><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><FONT face=\"Times New Roman\" size=3>Me maravilla que sigan apareciendo especies de animales nuevas; para eso Indonesia se las pinta sola, con sus m\u00e1s de diecisiete mil islas es un aut\u00e9ntico bazar del \u201canimal sin etiqueta\u201d. Quiero aclarar que lo que me gusta es que existan, no que las descubran. Ya s\u00e9 que no ve va a hacer caso los ansiosos hombres de la ciencia, pero les pedir\u00eda que no rastreen demasiado la zona, dej\u00e9mosles en la santa paz del anonimato, del que usted y yo ya hemos salido para siempre. Me apiado de la reci\u00e9n aparecida \u201cranita pinocho\u201d \u2013una de las especies que han visto la luz y el taqu\u00edgrafo por primera vez- , que viv\u00eda tan tranquila con una protuberancia en el morro que se hincha y apunta hacia arriba en \u00e9poca de celo. Con esa caracter\u00edstica, no s\u00e9 que pensar\u00e1n ustedes, pero yo preferir\u00eda no salir en ning\u00fan reportaje; p\u00f3nganse en su lugar, imaginen que la nariz se nos empinara cada vez que alguien nos gusta. S\u00ed, es como para <IMG class=imgdcha id=img_0 src=\"\/oscarterol\/wp-content\/uploads\/sites\/30\">quedarse en una selva a vivir y no salir nunca. Ahora, estos animalitos estar\u00e1n obligados a hacer \u201cla declaraci\u00f3n de la ciencia\u201d, o lo que es lo mismo: aparecer en los libros y en los documentales de la dos; ser estudiados en laboratorios as\u00e9pticos; y, si me apuran, portar un chip para que cualquier aspirante a F\u00e9lix Rodr\u00edguez de <?xml:namespace prefix = st1 ns = \"urn:schemas-microsoft-com:office:smarttags\" \/><st1:PersonName w:st=\"on\" ProductID=\"la Fuente\">la Fuente<\/st1:PersonName> les siga los pasos desde su ordenador. No comparto la obsesi\u00f3n de la ciencia por hacer el inventario del planeta, me parece m\u00e1s interesante pensar que existe el mundo desconocido con sus monstruos y sus plantas carn\u00edvoras capaces de tragarse a una persona. <<La curiosidad mat\u00f3 al gato>> y a la imaginaci\u00f3n. Es m\u00e1s, en mi barrio hay un dinosaurio que no se quiso extinguir por llevar la contraria al meteorito y no le damos ninguna importancia. Y si queremos explorar territorios in\u00e9ditos, arm\u00e9monos de valor y asom\u00e9monos a nuestra particular \u201cIndonesia interior\u201d, dentro de cada uno existen universos por descubrir y emociones por etiquetar. Pasen buen d\u00eda.<\/FONT><\/p>\n<p>A gozarla<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Poco a poco; s\u00ed, un corta pega de art\u00edculo con el detalle floral de una fotito, de acuerdo, pero lo importante es asomar. estoy convaleciente de un gran periodo de ausencia, joder, soy vasco y t\u00edmido, ahora no puedo desnudarme a la primera de cambio. Me siento como aquel marido que baj\u00f3 a por tabaco [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":42,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-347","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/posts\/347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/comments?post=347"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/posts\/347\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/media?parent=347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/categories?post=347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/tags?post=347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}