{"id":281,"date":"2010-10-24T23:54:00","date_gmt":"2010-10-24T23:54:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/oscarterol\/?p=281"},"modified":"2010-10-24T23:54:00","modified_gmt":"2010-10-24T23:54:00","slug":"aupa","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/oscarterol\/2010\/10\/24\/aupa\/","title":{"rendered":"Aupa!"},"content":{"rendered":"<p><P style=\"MARGIN: 0cm 0cm 0pt\" class=MsoNormal><SPAN lang=ES-TRAD><FONT size=3 face=Cambria><STRONG> <\/p>\n<p> <P style=\"MARGIN: 0cm 0cm 0pt\" class=MsoNormal>Buenos d\u00edas hermanos, aqu\u00ed dejo el art\u00edculo de hoy, calentito. Yo me meto a la cama que ma\u00f1ana tengo tute. Asomaremos la cabeza y a ver si no nos la cortan. Antonia 3 con la Hispania de los cojones, y Tele Esteban 5 con los morreos del principito y la del telediario, nosotros al contrataque con un bal\u00f3n y tres pelucas. En fin, que lucharemos hasta el pitido final. <\/p>\n<p> <P style=\"MARGIN: 0cm 0cm 0pt\" class=MsoNormal><\/STRONG><\/FONT><\/SPAN><STRONG> <\/p>\n<p> <P style=\"MARGIN: 0cm 0cm 0pt\" class=MsoNormal>Wikileaks<\/p>\n<p> <P style=\"MARGIN: 0cm 0cm 0pt\" class=MsoNormal><\/STRONG><SPAN lang=ES-TRAD><FONT size=3 face=Cambria>Si al leer esta palabra \u201cWikileaks\u201d ha sentido usted palpitaciones, sudoraci\u00f3n fr\u00eda, o ha corrido hacia su caja fuerte para ver si alguien la hubiera forzado, es se\u00f1al de que tiene algo que ocular \u2013 algo gordo, se entiende, de inter\u00e9s general, de amor\u00edo prohibido para arriba-. O lo que es lo mismo, est\u00e1 usted en el punto de mira del citado portal. Para que lo entiendan todos los lectores, Wikileaks es un portal de Internet a donde llegan documentos secretos para que dejen de serlo. Es decir, que si alguien tiene alg\u00fan secreto que no quiere llevarse a la tumba, lo mejor que puede hacer es enviarlo all\u00ed; tarde o temprano, cuando m\u00e1s escueza al sistema, lo airear\u00e1n a los cuatro vientos. Antiguamente, la tierra de la tumba tapaba la verdad y la mentira segu\u00eda viviendo hasta que le llegara \u201csu tierra\u201d; los papeles se quemaban y las pistas se borraban con incendios o bombazos. Se supon\u00eda que Dios o similar se encargar\u00eda de juzgar el caso y decidir\u00eda sobre la pena o la gloria del difunto. Hoy en d\u00eda, tenemos Internet, una posibilidad para que los esp\u00edritus hablen a los vivos y nos recuerden que el mundo lo controlan cuatro magnates despiadados que ser\u00edan capaces de cualquier barbaridad con tal de que sus fortunas sigan expandi\u00e9ndose. En otras palabras, que nos han pasado el marr\u00f3n a nosotros los simples peatones; ahora, Dios somos todos, eso s\u00ed, sin superpoderes ni licencia de milagro. Tenemos la informaci\u00f3n, la oficial que pagamos con el precio del peri\u00f3dico,<SPAN style=\"mso-spacerun: yes\">  <\/SPAN>y la secreta que mana de Internet, pero claro, no sabemos que hacer con tanta verdad. Me llamar\u00e1n rom\u00e1ntico, pero me parece m\u00e1s efectiva la revelaci\u00f3n que llega v\u00eda aparici\u00f3n mariana. S\u00ed, porque a\u00f1ade el componente de la fe y del misterio; necesidades b\u00e1sicas de nuestra existencia. Porque esa es la pregunta que todos nos estamos haciendo: Si todo est\u00e1 podrido y no somos mas que unas simples cobayas de un gran laboratorio de avariciosos, \u00bfen qu\u00e9 y en qui\u00e9n creer? La respuesta la ir\u00e9 desgranando a lo largo de los miles de art\u00edculos que nos quedan por compartir. Pasen buen d\u00eda. Ah, el bueno<SPAN style=\"mso-spacerun: yes\">  <\/SPAN>de esta pel\u00edcula es usted.<\/FONT><\/SPAN><\/p>\n<p> <P style=\"MARGIN: 0cm 0cm 0pt\" class=MsoNormal><SPAN lang=ES-TRAD><FONT size=3 face=Cambria><\/FONT><\/SPAN> <\/p>\n<p> <P style=\"MARGIN: 0cm 0cm 0pt\" class=MsoNormal><SPAN lang=ES-TRAD><FONT size=3 face=Cambria>NOS SEGUIMOS ENCONTRANDO POR AQU\u00cd. UN ABRAZO DE OSOOOOOOOOOOO<\/FONT><\/SPAN><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Buenos d\u00edas hermanos, aqu\u00ed dejo el art\u00edculo de hoy, calentito. Yo me meto a la cama que ma\u00f1ana tengo tute. Asomaremos la cabeza y a ver si no nos la cortan. Antonia 3 con la Hispania de los cojones, y Tele Esteban 5 con los morreos del principito y la del telediario, nosotros al contrataque [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":42,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-281","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/posts\/281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/comments?post=281"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/posts\/281\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/media?parent=281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/categories?post=281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/oscarterol\/wp-json\/wp\/v2\/tags?post=281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}