{"id":135,"date":"2008-02-11T14:46:00","date_gmt":"2008-02-11T14:46:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/labiologiaestupenda\/?p=135"},"modified":"2008-02-11T14:46:00","modified_gmt":"2008-02-11T14:46:00","slug":"agua-bendita","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/2008\/02\/11\/agua-bendita\/","title":{"rendered":"Agua bendita"},"content":{"rendered":"<p>En febrero de 1989 ingres\u00f3 en el Hospital de Birmingham, en Inglaterra, un joven  de 19 a\u00f1os que se hab\u00eda arrojado desde la d\u00e9cima planta del edificio en que  viv\u00eda. Ingres\u00f3 con heridas muy graves de las que fue mejorando despu\u00e9s de varias  operaciones y de padecer una neumon\u00eda. Sin embargo, a las seis semanas volvi\u00f3 a  enfermar de neumon\u00eda y, en esta ocasi\u00f3n, causada por <em><A href=\"http:\/\/textbookofbacteriology.net\/pseudomonas.html\">Pseudomonas  aeruginosa<\/a><\/em>, infecci\u00f3n que siempre se trata de evitar en las unidades de  cuidados intensivos. Ian Greaves y K.M. Porter, ortop\u00e9dico y cirujano  respectivamente del citado hospital, fueron los encargados de averiguar c\u00f3mo se  hab\u00eda producido la infecci\u00f3n. No hab\u00eda m\u00e1s pacientes con la misma enfermedad y  no encontraron la manera de detectar el origen de la infecci\u00f3n. Pero uno de los  autores fue testigo de la visita al paciente de una t\u00eda y de c\u00f3mo \u00e9sta lo  asperjaba generosamente con agua bendita. Inmediatamente se envi\u00f3 lo que quedaba  del agua bendita al laboratorio de microbiolog\u00eda y se detect\u00f3 la  <em>Pseudomonas<\/em> en el recipiente. La t\u00eda dej\u00f3 de bendecir al paciente y  este se recuper\u00f3; a los tres meses fue dado de alta.<br \/>\nLos autores aseguran que  no conocen otro caso de transmisi\u00f3n de una infecci\u00f3n por medio del agua bendita  y sospechan que este hecho puede ser m\u00e1s habitual de lo que se cree. Y tienen  raz\u00f3n: en 1996, J.C. Rees y K.D. Allen, del Hospital Whiston, de Prescot, en  Inglaterra, relatan el caso de un hombre de 53 a\u00f1os, con graves quemaduras en el  80% del cuerpo, que contrae una infecci\u00f3n con <A href=\"http:\/\/www.seimc.org\/control\/revi_Bacte\/acinetobacter.htm\"><em>Acinetobacter  baumanii<\/em> <\/a>debido al agua bendita con la que le roc\u00edan sus familiares.  Para constatar si el problema est\u00e1 m\u00e1s extendido, los autores analizan el agua  bendita de 13 iglesias (nueve de Londres, dos de Walsigham y dos del R\u00edo Jord\u00e1n)  y encuentran <em>Pseudomonas aeruginosa<\/em>, <A href=\"http:\/\/www.antibioticoterapia.com\/modules.php?name=News&#038;file=article&#038;sid=582&#038;num=2006-03-01\"><em>Enterobacter<\/em>  <\/a>spp., <em><A href=\"http:\/\/www.nlm.nih.gov\/medlineplus\/spanish\/ecoliinfections.html\">Escherichia  coli<\/a><\/em>, <A href=\"http:\/\/hmsc.oregonstate.edu\/classes\/MB492\/hydrophilahayes\/\"><em>Aeromonas  hydrophila<\/em> <\/a>y el hongo <A href=\"http:\/\/www.buenasalud.com\/lib\/ShowDoc.cfm?LibDocID=3395&#038;ReturnCatID=4\"><em>Candida<\/em>  <\/a>sp. En resumen, el agua bendita es un factor de riesgo de infecci\u00f3n en los  hospitales. Parecidos resultados se han obtenido con el agua bendita de Alemania  seg\u00fan asegura F.D. Daschner, del Hospital Cl\u00ednico de la Universidad  Albert-Ludwigs, de Freiburg, despu\u00e9s de analizar diez muestras de hospitales e  iglesias.<br \/>\nPero no s\u00f3lo es un riesgo para la salud el agua bendita hisopeada  sobre los enfermos de un hospital, tambi\u00e9n lo es la que se encuentra en las  pilas de las iglesias. Doug Payne, de Dublin, nos cuenta c\u00f3mo, dentro de una  Feria de Ciencias para j\u00f3venes, se han realizado estudios sobre las pilas de  agua bendita de iglesias de varios lugares de Irlanda y se han encontrado,  adem\u00e1s de basura de todo tipo, gusanos verdes, huevos de estos gusanos verdes y,  en an\u00e1lisis microbiol\u00f3gicos, coliformes, estafilococos, levaduras y hongos. Las  j\u00f3venes que hicieron el trabajo piden a los encargados de las pilas de agua  bendita que, por lo menos, quiten las part\u00edculas que sean tan grandes como para  verse a simple vista. Adem\u00e1s, estas pilas son utilizadas por drogadictos para  lavar las jeringuillas que usan para inyectarse hero\u00edna.<br \/>\nUn an\u00e1lisis similar  hecho en las iglesias de Sevilla por V. Jurado y su grupo, del <A href=\"http:\/\/www.irnase.csic.es\/index.html\">Instituto de Recursos Naturales y  Agrobiolog\u00eda<\/a>, descubri\u00f3 una fuerte contaminaci\u00f3n bacteriana. Se encontraron  coliformes, Enterobacteriaceae y otras bacterias pat\u00f3genas, hasta 30 de las 37  especies aisladas. Y en M\u00e9xico, en un manantial en Tlacote, a unos doez  kil\u00f3metros de Quer\u00e9taro y al norte de Ciudad de M\u00e9xico, del que mana agua  milagrosa que hay que beber para que se produzca el milagro, se han detectado  casos de amebiasis por <em><A href=\"http:\/\/www.zonapediatrica.com\/parasitosis\/amebiasis-entamoeba-histolytica.html\">Entamoeba  histolytica<\/a>,<\/em> seg\u00fan nos cuentan Sharon Reed y su grupo, del Centro  M\u00e9dico de la Universidad de California en San Diego.<br \/>\nPero todo lo relacionado  con el agua bendita no puede ser tan desagradable. Sandra Lenington, de la  Universidad de Santa Clara, sospech\u00f3 que el agua bendita ayudar\u00eda a crecer  r\u00e1pida y sana una plantaci\u00f3n de r\u00e1banos y, para constatarlo, reg\u00f3 doce plantas  con agua bendita y otras doce con agua del grifo. No encontr\u00f3 diferencias en el  crecimiento de ambos grupos. Y curiosamente public\u00f3 los resultados en una  revista de psicolog\u00eda.<\/p>\n<p>*Daschner, F.D. 1997. Holy water, tap water,  mineral water or water filters? <em>Journal of Hospital Infection<\/em>  35:71-72.<br \/>\n*Greaves, I. &#038; K.M. Porter. 1992. Holy spirit? An unusual cause  of pseudomonal infection in a multiply injured patient. <em>British Medical  Journal<\/em> 305: 1578.<br \/>\n*Jurado, V., A. Ort\u00edz-Mart\u00ednez, M. Gonz\u00e1lez-delValle,  B. Hermos\u00edn &#038; C. Saiz-Jim\u00e9nez. 2002. Holy water fonts are reservoirs of  pathogenic bacteria. <em>Environmental Microbiology<\/em> 4: 617-620. *Lenington,  S. 1979. Effect of holy water on the growth of radish plants. <em>Psychological  Reports<\/em> 45: 381-382.<br \/>\n*Payne, D. 2001. Holy water not always a blessing.  <em>British Medical Journal<\/em> 322: 190.<br \/>\n*Reed, S.L., C.E. Davis &#038; H.  Jinich. 1995. Amebiasis from the &#8220;<A href=\"http:\/\/www.share-es.org\/tlacote.htm?mn=8&#038;sm=8-3\">Miraculous Water of  Tlacote<\/a>&#8220;. <em>New England Journal of Medicine<\/em> 332: 687-688.<br \/>\n*Rees,  J.C. &#038; K.D. Allen. 1996. Holy water &#8211; a risk factor for hospital-acquired  infection. <em>Journal of Hospital Infection<\/em> 32: 51-55.<br \/>\n*Shirrell  Kaswell, A. 2001. Healthy holy water. <em>Cincinnati Skeptics<\/em> 10: 9. <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En febrero de 1989 ingres\u00f3 en el Hospital de Birmingham, en Inglaterra, un joven de 19 a\u00f1os que se hab\u00eda arrojado desde la d\u00e9cima planta del edificio en que viv\u00eda. Ingres\u00f3 con heridas muy graves de las que fue mejorando despu\u00e9s de varias operaciones y de padecer una neumon\u00eda. Sin embargo, a las seis semanas [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-135","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/posts\/135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/comments?post=135"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/posts\/135\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/media?parent=135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/categories?post=135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/tags?post=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}