{"id":123,"date":"2010-07-16T15:13:00","date_gmt":"2010-07-16T15:13:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/labiologiaestupenda\/?p=123"},"modified":"2010-07-16T15:13:00","modified_gmt":"2010-07-16T15:13:00","slug":"lobos","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/2010\/07\/16\/lobos\/","title":{"rendered":"Lobos"},"content":{"rendered":"<p>Los lobos (<EM>Canis lupus<\/EM>) son animales emblem\u00e1ticos que han dejado recuerdos, tradiciones y leyendas en los lugares de donde han desparecido. Los pueblos de agricultores y ganaderos los vieron como competidores y procuraron su eliminaci\u00f3n. As\u00ed ocurri\u00f3 en el Pa\u00eds Vasco. El trabajo de investigaci\u00f3n de Jos\u00e9 Mar\u00eda Fern\u00e1ndez y Nerea Ruiz de Azua, del Instituto Alav\u00e9s de la Naturaleza, de Vitoria, explica las razones de esa desaparici\u00f3n. Han revisado las actas de los ayuntamientos en las que aparecen los pagos que se hac\u00edan a los alima\u00f1eros por pieza cazada, habitualmente por lobos y zorros. Entre 1805 y 1905 encuentran 203 citas con los gastos debidos a la muerte de 308 lobos. El 54.5% han sido capturados con trampas, el 15.1% en batidas y el 16.9% por batidas en las tradicionales <A id=link_0 title=http:\/\/dionisa.lacoctelera.net\/post\/2009\/02\/18\/las-loberas-afortunadamente-la-actualidad-solo-interes href=\"http:\/\/dionisa.lacoctelera.net\/post\/2009\/02\/18\/las-loberas-afortunadamente-la-actualidad-solo-interes\">loberas<\/A>. S\u00f3lo el 1,2% muri\u00f3 por envenenamiento; el veneno habitual era la estricnina.<\/p>\n<p>En el mismo periodo de tiempo se capturan 59 camadas, con 257 cr\u00edas (no incluidas en la cuenta de adultos), pero su captura va disminuyendo con el tiempo. Lo mismo ocurre con la proporci\u00f3n entre machos y hembras en los adultos y, a principios del siglo XX, ya s\u00f3lo se capturan machos. Por tanto, la poblaci\u00f3n disminuye, las hembras son cada vez m\u00e1s escasas y s\u00f3lo quedan machos itinerantes cada vez m\u00e1s aislados. Seg\u00fan los autores, a pesar de la presi\u00f3n cineg\u00e9tica sobre los lobos y teniendo en cuenta que el uso de veneno es raro, estos no deber\u00edan haber desaparecido si no fuese porque, a la vez, han disminuido sus presas, sobre todo el ganado que pasta libre en los montes comunes.<\/p>\n<p>Pero los lobos han vuelto. Desde finales del siglo pasado, los lobos han vuelto a deambular por el norte de Burgos y el oeste y norte de Alava. Jorge Echegaray y sus colaboradores, del Grupo Lobo de Euskadi, de Vitoria, han comenzado a estudiar esta nueva expansi\u00f3n del emblem\u00e1tico cazador. El m\u00e9todo habitual de hacer recuentos en poblaciones de lobos pasa por localizar grupos familiares y calcular el n\u00famero de individuos por grupo. Sin embargo, en la zona de expansi\u00f3n del lobo hacia el Pa\u00eds Vasco, el n\u00famero de lobos es peque\u00f1o y la movilidad muy grande, por lo que Echegaray y su equipo han tenido que desarrollar una t\u00e9cnica diferente. Han decidido recoger heces y, a partir del an\u00e1lisis del ADN en cada recogida, identificar individuos y hacer el recuento. Este m\u00e9todo, al identificar a cada individuo, permite adem\u00e1s seguir sus movimientos por el territorio estudiado.<\/p>\n<p>Despu\u00e9s de recorrer 690 kil\u00f3metros, los autores recogen 136 muestras de heces, y de ellas, consiguen el estudio gen\u00e9tico de 86. Corresponden al lobo 31 muestras; al zorro, dos muestras; y al perro, 53 muestras. En las muestras de lobo se hace el estudio detallado para identificar individuos y se encuentran 16 genotipos diferentes, entre ellos cinco machos y siete hembras. Tres de ellos se han localizado varias veces y, en un caso, una hembra ha recorrido en cinco semanas unos 25 kil\u00f3metros por lo menos.<\/p>\n<p>Dos datos m\u00e1s: la mayor\u00eda de las muestras de lobo contienen restos de animales salvajes (corzo sobre todo) mientras que en la mayor\u00eda de las muestras de perro, los restos son de animales dom\u00e9sticos (oveja). En este periodo de tiempo, el n\u00famero de mastines subvencionados para proteger del lobo los reba\u00f1os era de 153. Y, en segundo lugar, los autores calculan que el precio por conservar esta especie supone unos 3000 euros por lobo y por a\u00f1o, seg\u00fan las indemnizaciones pagadas en el periodo 2003-2004. En ese periodo hubo 163 ataques al ganado y el 95% se atribuy\u00f3 al lobo. Estas cifras no se corresponden con los restos identificados en las heces. Sin embargo, hay que tener en cuenta que el due\u00f1o del ganado s\u00f3lo recibe subvenci\u00f3n en el caso de ataque por el lobo.<\/p>\n<p> *Echegaray, J., A. Illana, A. Hernando, F. Mart\u00ednez de Lecea, J. Bayona, I. Covela, J.A. de la Torre, D. paniagua &#038; C. Vil\u00e0. 2007. Uso de t\u00e9cnicas gen\u00e9ticas no invasivas para estimar el tama\u00f1o y la distribuci\u00f3n del lobo (<EM>Canis lupus <\/EM>Linnaeus, 1758) en el Pa\u00eds Vasco (N Espa\u00f1a). <EM>Galemys <\/EM>19: 3-18.<br \/>\n*Echegaray, J. &#038; C. Vil\u00e0. 2010. Noninvasive monitoring of wolves at the edge of their distribution and the cost of their conservation. <EM>Animal Conservation <\/EM>13: 157-161.<br \/>\n*Fern\u00e1ndez, J.M. &#038; N. Ruiz de Azua. 2010. Historical dynamics of a declining wolf population: persecution vs. prey reduction. <EM>European Journal of Wildlife Research <\/EM>56: 169-176.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Los lobos (Canis lupus) son animales emblem\u00e1ticos que han dejado recuerdos, tradiciones y leyendas en los lugares de donde han desparecido. Los pueblos de agricultores y ganaderos los vieron como competidores y procuraron su eliminaci\u00f3n. As\u00ed ocurri\u00f3 en el Pa\u00eds Vasco. El trabajo de investigaci\u00f3n de Jos\u00e9 Mar\u00eda Fern\u00e1ndez y Nerea Ruiz de Azua, del [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-123","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/posts\/123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/comments?post=123"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/posts\/123\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/media?parent=123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/categories?post=123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/labiologiaestupenda\/wp-json\/wp\/v2\/tags?post=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}