{"id":5152,"date":"2018-02-03T07:00:16","date_gmt":"2018-02-03T06:00:16","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=5152"},"modified":"2018-02-03T07:00:16","modified_gmt":"2018-02-03T06:00:16","slug":"lomo-calabacin-y-brocoli-rebozados","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2018\/02\/03\/lomo-calabacin-y-brocoli-rebozados\/","title":{"rendered":"Lomo, calabac\u00edn y br\u00f3coli rebozados"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5153\" src=\"\/\/blogs.elcorreo.com\/jorbasmar\/wp-content\/uploads\/sites\/153\/2018\/02\/Lomo-calabacin-y-brocoli-rebozados-300x200.jpg\" alt=\"lomo-calabacin-y-brocoli-rebozados\" width=\"300\" height=\"200\" srcset=\"\/wp-content\/uploads\/\/sites\/153\/2018\/02\/Lomo-calabacin-y-brocoli-rebozados-300x200.jpg 300w, \/wp-content\/uploads\/\/sites\/153\/2018\/02\/Lomo-calabacin-y-brocoli-rebozados.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Hoy os traigo un plato sencillo, rico y adem\u00e1s una forma de hacer comer verduras a los poco adictos a ellas como yo.<\/p>\n<p>Realmente cocine m\u00e1s cantidad de verduras y lomo para futuras recetas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>6 filetes de lomo de cerdo<\/strong><\/p>\n<p><strong>1\/2 calabac\u00edn<\/strong><\/p>\n<p><strong>2 ramilletes de br\u00f3coli cocido<\/strong><\/p>\n<p><strong>1 tomate<\/strong><\/p>\n<p><strong>Aceite de girasol<\/strong><\/p>\n<p><strong>1 huevo<\/strong><\/p>\n<p><strong>Harina<\/strong><\/p>\n<p><strong>Pan rallado<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Comenzamos por cocer al vapor el br\u00f3coli (coliflor verde) y dejamos enfriar.<\/p>\n<p>Colocamos abundante aceite en una sart\u00e9n para fre\u00edr la carne y las verduras.<\/p>\n<p>Salamos la carne, la pasamos por huevo, harina y fre\u00edmos en el aceite.<\/p>\n<p>Cortamos el calabac\u00edn primero a lonchas gruesas y despu\u00e9s a tiritas, como si cort\u00e1ramos patatas para fre\u00edr.<\/p>\n<p>Salamos el calabac\u00edn, pasamos cara tirita de calabac\u00edn por huevo y \u00a0pan rallado, fri\u00e9ndolo en el aceite de la carne.<\/p>\n<p>A continuaci\u00f3n cortamos el br\u00f3coli en ramilletes sal\u00e1ndolo y lo pasamos tambi\u00e9n por harina, huevo y fre\u00edmos en el mismo aceite.<\/p>\n<p>Abrimos un tomate por la mitad, lo salamos y tambi\u00e9n lo fre\u00edmos, tapado a fuego lento en el mismo aceite.<\/p>\n<p>Servimos 3 filetes por comensal, un pu\u00f1adito de tiras de calabac\u00edn, medio tomate y un trocito de br\u00f3coli en cada plato.<\/p>\n<p>El tomate esta delicioso mojando sopitas en \u00e9l.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy os traigo un plato sencillo, rico y adem\u00e1s una forma de hacer comer verduras a los poco adictos a ellas como yo. Realmente cocine m\u00e1s cantidad de verduras y lomo para futuras recetas. &nbsp; Ingredientes (2 personas): \u00a0 6 filetes de lomo de cerdo 1\/2 calabac\u00edn 2 ramilletes de br\u00f3coli cocido 1 tomate Aceite [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-5152","post","type-post","status-publish","format-standard","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/5152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=5152"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/5152\/revisions"}],"predecessor-version":[{"id":5154,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/5152\/revisions\/5154"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=5152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=5152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=5152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}