{"id":5118,"date":"2018-01-22T07:02:53","date_gmt":"2018-01-22T06:02:53","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=5118"},"modified":"2018-01-22T07:02:53","modified_gmt":"2018-01-22T06:02:53","slug":"queso-fresco-casero-con-maracuya","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2018\/01\/22\/queso-fresco-casero-con-maracuya\/","title":{"rendered":"Queso fresco casero con maracuya"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5119\" src=\"\/\/blogs.elcorreo.com\/jorbasmar\/wp-content\/uploads\/sites\/153\/2018\/01\/Queso-fresco-casero-con-maracuya-300x200.jpg\" alt=\"queso-fresco-casero-con-maracuya\" width=\"300\" height=\"200\" srcset=\"\/wp-content\/uploads\/\/sites\/153\/2018\/01\/Queso-fresco-casero-con-maracuya-300x200.jpg 300w, \/wp-content\/uploads\/\/sites\/153\/2018\/01\/Queso-fresco-casero-con-maracuya.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Hac\u00eda tiempo que no realizo queso fresco casero, en esta ocasi\u00f3n he optado por realizarlo con yogurt de maracuy\u00e1 y sin utilizar el microondas.<\/p>\n<p>Para realizar esta receta ser\u00e1 necesario un term\u00f3metro de cocina, para controlar que la leche no supere los 80\u00ba cent\u00edgrados.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>1,5 litros de leche de vaca de tetrabrik<\/strong><\/p>\n<p><strong>1 lim\u00f3n<\/strong><\/p>\n<p><strong>1 yogurt de maracuy\u00e1 (puede ser natural o de otro sabor)<\/strong><\/p>\n<p><strong>1 cucharada sopera de cuajo (no es imprescindible)<\/strong><\/p>\n<p><strong>2 cucharaditas de sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Colocamos la leche, el yogur, el cuajo y el zumo colado del lim\u00f3n en una olla.<\/p>\n<p>Calentamos la leche a fuego medio, hasta que alcance los 80\u00ba, en ese momento, tapamos la olla y retiramos del fuego, hasta que la leche se enfri\u00e9.<\/p>\n<p>Una vez fr\u00eda la leche (estar\u00e1 cortada a causa principalmente del lim\u00f3n), a\u00f1adimos la sal y removemos.<\/p>\n<p>Solo resta colocar el contenido de la olla en un colador grande, para separar el suero (agua de la leche que se puede utilizar para realizar bizcochos).<\/p>\n<p>Dejamos escurrir bien hasta que el contenido del colador se solidifique.<\/p>\n<p>Volcamos en contenido del colador con cuidado de no romperlo en un plato con pared, probablemente nos siga soltando suero, que iremos retirando peri\u00f3dicamente.<\/p>\n<p>Guardar en el frigor\u00edfico un d\u00eda o dos, para que termine de solidificarse, o hasta que os guste su textura.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hac\u00eda tiempo que no realizo queso fresco casero, en esta ocasi\u00f3n he optado por realizarlo con yogurt de maracuy\u00e1 y sin utilizar el microondas. Para realizar esta receta ser\u00e1 necesario un term\u00f3metro de cocina, para controlar que la leche no supere los 80\u00ba cent\u00edgrados. &nbsp; Ingredientes: \u00a0 1,5 litros de leche de vaca de tetrabrik [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-5118","post","type-post","status-publish","format-standard","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/5118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=5118"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/5118\/revisions"}],"predecessor-version":[{"id":5120,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/5118\/revisions\/5120"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=5118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=5118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=5118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}