{"id":5080,"date":"2018-01-12T07:19:42","date_gmt":"2018-01-12T06:19:42","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=5080"},"modified":"2018-01-12T07:19:42","modified_gmt":"2018-01-12T06:19:42","slug":"bocadillo-de-sobras-de-pechuga-y-tocino","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2018\/01\/12\/bocadillo-de-sobras-de-pechuga-y-tocino\/","title":{"rendered":"Bocadillo de sobras de pechuga y tocino"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5081\" src=\"\/\/blogs.elcorreo.com\/jorbasmar\/wp-content\/uploads\/sites\/153\/2018\/01\/Bocadillo-de-sobras-de-pechuga-y-tocino-300x200.jpg\" alt=\"bocadillo-de-sobras-de-pechuga-y-tocino\" width=\"300\" height=\"200\" srcset=\"\/wp-content\/uploads\/\/sites\/153\/2018\/01\/Bocadillo-de-sobras-de-pechuga-y-tocino-300x200.jpg 300w, \/wp-content\/uploads\/\/sites\/153\/2018\/01\/Bocadillo-de-sobras-de-pechuga-y-tocino.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Si presentamos en la mesa unos filetes de pechuga rebozados de hace un d\u00eda o dos, se ve poco apetecible en la mesa, pero si la arreglamos un poco y la servimos en bocadillo, seguro que todos se chupan los dedos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 bocadillos):<\/strong><\/p>\n<p><strong>2 lonchas de panceta<\/strong><\/p>\n<p><strong>4 filetes de pechuga de pollo rebozada (sobrantes de otro d\u00eda)<\/strong><\/p>\n<p><strong>2 panecillos de bocadillo<\/strong><\/p>\n<p><strong>1 tomate<\/strong><\/p>\n<p><strong>Lechuga<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Colocamos un chorrito de aceite en una sart\u00e9n y doramos en ella la panceta.<\/p>\n<p>Cuando la panceta est\u00e9 casi lista calentamos en su aceite los filetes de pechuga.<\/p>\n<p>Mientras troceamos el tomate y lo colocamos en el vaso de la batidora.<\/p>\n<p>Cuando los filetes de pechuga est\u00e9n calientes, reservamos junto a la panceta y a\u00f1adimos el aceite sobrante al tomate, si lo deseamos podemos agregar mas aceite crudo, salamos y trituramos.<\/p>\n<p>Abrimos por la mitad cada panecillo y untamos estos con la salsa de tomate que hemos preparado.<\/p>\n<p>Cortamos la corteza de la panceta y colocamos una loncha en cada panecillo.<\/p>\n<p>Cubrimos la panceta con los filetes de pechuga.<\/p>\n<p>A\u00f1adimos la lechuga y cortamos en tres trozos cada panecillo para poder comerlos con facilidad.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/1.bp.blogspot.com\/-UFVs2xCqEbs\/WlhPTGlIuGI\/AAAAAAAAKeI\/vPeeUIgPUWMgyC27DSjIgu1CFDyvxQLDwCLcBGAs\/s320\/Bocadillo%2Bde%2Bsobras%2Bde%2Bpechuga%2By%2Btocino.jpg\" rel=\"external nofollow\">https:\/\/1.bp.blogspot.com\/-UFVs2xCqEbs\/WlhPTGlIuGI\/AAAAAAAAKeI\/vPeeUIgPUWMgyC27DSjIgu1CFDyvxQLDwCLcBGAs\/s320\/Bocadillo%2Bde%2Bsobras%2Bde%2Bpechuga%2By%2Btocino.jpg<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Si presentamos en la mesa unos filetes de pechuga rebozados de hace un d\u00eda o dos, se ve poco apetecible en la mesa, pero si la arreglamos un poco y la servimos en bocadillo, seguro que todos se chupan los dedos. &nbsp; Ingredientes (2 bocadillos): 2 lonchas de panceta 4 filetes de pechuga de pollo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-5080","post","type-post","status-publish","format-standard","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/5080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=5080"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/5080\/revisions"}],"predecessor-version":[{"id":5082,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/5080\/revisions\/5082"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=5080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=5080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=5080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}