{"id":4998,"date":"2017-12-18T07:01:01","date_gmt":"2017-12-18T06:01:01","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4998"},"modified":"2017-12-18T07:01:01","modified_gmt":"2017-12-18T06:01:01","slug":"salsa-romesco","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2017\/12\/18\/salsa-romesco\/","title":{"rendered":"Salsa romesco"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4999\" src=\"\/\/blogs.elcorreo.com\/jorbasmar\/wp-content\/uploads\/sites\/153\/2017\/12\/Salsa-romesco-300x200.jpg\" alt=\"salsa-romesco\" width=\"300\" height=\"200\" srcset=\"\/wp-content\/uploads\/\/sites\/153\/2017\/12\/Salsa-romesco-300x200.jpg 300w, \/wp-content\/uploads\/\/sites\/153\/2017\/12\/Salsa-romesco.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>La salsa romesco es una deliciosa salsa que se acostumbra a utilizar en Catalu\u00f1a para acompa\u00f1ar a los t\u00edpicos cal\u00e7ots.<\/p>\n<p>En la actualidad (al menos en Catalu\u00f1a), se puede encontrar preparada esta salsa en los supermercados, suele estar bastante lograda, pero claro, como la casera ninguna.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>2 \u00f1oras<\/strong><\/p>\n<p><strong>2 tomates<\/strong><\/p>\n<p><strong>1 cabeza de ajos<\/strong><\/p>\n<p><strong>12 almendras tostadas, sin piel<\/strong><\/p>\n<p><strong>12 avellanas tostadas, sin piel<\/strong><\/p>\n<p><strong>1 rebanada de pan frito<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Vinagre de M\u00f3dena<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>La preparaci\u00f3n de la salsa es un poco trabajosa, pero por un d\u00eda, trabajaremos en la cocina.<\/p>\n<p>Comenzamos por colocar las \u00f1oras secas (pimientos choriceros), en agua 24 horas antes de utilizarlas, tambi\u00e9n podemos acelerar el proceso introduci\u00e9ndolas sumergidas en agua en el microondas, en tandas de 3 minutos, hasta que se hidraten y se pongan tiernas.<\/p>\n<p>Dejamos enfriar las \u00f1oras si las hemos hidratado al microondas, rascamos su carne con la ayuda de un cuchillo, desechando la piel y reservamos.<\/p>\n<p>Desgranamos un cabeza de ajos, reservando dos dientes y colocando el resto de ajos en la placa del horno, a\u00f1adimos a la placa 2 tomates (podemos poner m\u00e1s verduras para futuras recetas) y horneamos a 160\u00ba hasta que los tomates est\u00e9n blandos y podamos pelarlos con facilidad, si los ajos se nos hacen antes, los retiramos antes que se nos quemen, cuando est\u00e9n tiernos.<\/p>\n<p>Mientras colocamos en un almirez, el pan frito, los dos dientes de ajos crudos, las avellanas, las almendras y machacamos bien.<\/p>\n<p>Pasamos el contenido del almirez al vaso de la batidora.<\/p>\n<p>Pelamos los tomates y los ajos que hemos horneado, uni\u00e9ndolos a la salsa que tenemos en el vaso de la batidora.<\/p>\n<p>A\u00f1adimos un generoso chorro de vinagre y sal.<\/p>\n<p>Trituramos con la batidora y vamos agregando en chorrito aceite de oliva, hasta que la salsa tenga la textura deseada.<\/p>\n<p>Probar y rectificar el punto de sal, vinagre y aceite.<\/p>\n<p>Solo resta dejarla enfriar y ponerse a mojar sopitas en ella.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La salsa romesco es una deliciosa salsa que se acostumbra a utilizar en Catalu\u00f1a para acompa\u00f1ar a los t\u00edpicos cal\u00e7ots. En la actualidad (al menos en Catalu\u00f1a), se puede encontrar preparada esta salsa en los supermercados, suele estar bastante lograda, pero claro, como la casera ninguna. &nbsp; Ingredientes: \u00a0 2 \u00f1oras 2 tomates 1 cabeza [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-4998","post","type-post","status-publish","format-standard","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4998"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4998\/revisions"}],"predecessor-version":[{"id":5000,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4998\/revisions\/5000"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}