{"id":4929,"date":"2017-11-27T06:56:15","date_gmt":"2017-11-27T05:56:15","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4929"},"modified":"2017-11-27T06:56:15","modified_gmt":"2017-11-27T05:56:15","slug":"dados-de-sandia-con-sangria","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2017\/11\/27\/dados-de-sandia-con-sangria\/","title":{"rendered":"Dados de sand\u00eda con sangr\u00eda"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4930\" src=\"\/\/blogs.elcorreo.com\/jorbasmar\/wp-content\/uploads\/sites\/153\/2017\/11\/Dados-de-sandia-con-sangria-300x200.jpg\" alt=\"dados-de-sandia-con-sangria\" width=\"300\" height=\"200\" srcset=\"\/wp-content\/uploads\/\/sites\/153\/2017\/11\/Dados-de-sandia-con-sangria-300x200.jpg 300w, \/wp-content\/uploads\/\/sites\/153\/2017\/11\/Dados-de-sandia-con-sangria.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Nada m\u00e1s simple que la realizaci\u00f3n de este f\u00e1cil postre.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>1 rodaja de sand\u00eda (sin semillas)<\/strong><\/p>\n<p><strong>2 cucharadas soperas de az\u00facar<\/strong><\/p>\n<p><strong>Sangr\u00eda<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Cortamos una rodaja de sand\u00eda, como si cort\u00e1ramos una rodaja de pi\u00f1a, para cortarle la piel y posteriormente cortar la sand\u00eda a tiras (como si fueran patatas fritas gordas) y posteriormente cortar las tiras a daditos, para que nos quede cortada en forma de daditos.<\/p>\n<p>Solo nos resta repartir los daditos entre dos copas, colocamos una cucharada sopera de az\u00facar en cada copa y rellenamos de sangr\u00eda.<\/p>\n<p>Servir fr\u00edo.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Nada m\u00e1s simple que la realizaci\u00f3n de este f\u00e1cil postre. &nbsp; Ingredientes (2 personas): \u00a0 1 rodaja de sand\u00eda (sin semillas) 2 cucharadas soperas de az\u00facar Sangr\u00eda \u00a0 Preparaci\u00f3n: \u00a0 Cortamos una rodaja de sand\u00eda, como si cort\u00e1ramos una rodaja de pi\u00f1a, para cortarle la piel y posteriormente cortar la sand\u00eda a tiras (como si [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-4929","post","type-post","status-publish","format-standard","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4929"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4929\/revisions"}],"predecessor-version":[{"id":4931,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4929\/revisions\/4931"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}