{"id":4883,"date":"2017-11-15T07:02:19","date_gmt":"2017-11-15T06:02:19","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4883"},"modified":"2017-11-15T07:02:19","modified_gmt":"2017-11-15T06:02:19","slug":"batido-de-apio-y-pepino","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2017\/11\/15\/batido-de-apio-y-pepino\/","title":{"rendered":"Batido de apio y pepino"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4884\" src=\"\/\/blogs.elcorreo.com\/jorbasmar\/wp-content\/uploads\/sites\/153\/2017\/11\/Batido-de-apio-y-pepino-300x200.jpg\" alt=\"batido-de-apio-y-pepino\" width=\"300\" height=\"200\" srcset=\"\/wp-content\/uploads\/\/sites\/153\/2017\/11\/Batido-de-apio-y-pepino-300x200.jpg 300w, \/wp-content\/uploads\/\/sites\/153\/2017\/11\/Batido-de-apio-y-pepino.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Hoy os traigo un estupendo batido muy f\u00e1cil de realizar y de muy agradable sabor para el paladar.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (4 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>5 o 6 pencas de apio<\/strong><\/p>\n<p><strong>1 pepino<\/strong><\/p>\n<p><strong>2 yogures naturales<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Vinagre<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Lavamos las pencas del apio y las introducimos en la licuadora.<\/p>\n<p>Lavamos y troceamos el pepino sin pelarlo y tambi\u00e9n lo introducimos en la licuadora uniendo al apio.<\/p>\n<p>A\u00f1adimos los yogures, la sal, aceite y vinagre al gusto, mezclamos bien y guardamos en el frigor\u00edfico para servir bien fr\u00edo.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy os traigo un estupendo batido muy f\u00e1cil de realizar y de muy agradable sabor para el paladar. &nbsp; Ingredientes (4 personas): \u00a0 5 o 6 pencas de apio 1 pepino 2 yogures naturales Aceite de oliva Vinagre Sal \u00a0 Preparaci\u00f3n: \u00a0 Lavamos las pencas del apio y las introducimos en la licuadora. Lavamos y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-4883","post","type-post","status-publish","format-standard","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4883"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4883\/revisions"}],"predecessor-version":[{"id":4885,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4883\/revisions\/4885"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}