{"id":4826,"date":"2017-10-30T07:05:34","date_gmt":"2017-10-30T06:05:34","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4826"},"modified":"2017-10-30T07:05:34","modified_gmt":"2017-10-30T06:05:34","slug":"copa-de-fresas-con-higos","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2017\/10\/30\/copa-de-fresas-con-higos\/","title":{"rendered":"Copa de fresas con higos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4827\" src=\"\/\/blogs.elcorreo.com\/jorbasmar\/wp-content\/uploads\/sites\/153\/2017\/10\/Copa-de-fresas-con-higos-300x200.jpg\" alt=\"copa-de-fresas-con-higos\" width=\"300\" height=\"200\" srcset=\"\/wp-content\/uploads\/\/sites\/153\/2017\/10\/Copa-de-fresas-con-higos-300x200.jpg 300w, \/wp-content\/uploads\/\/sites\/153\/2017\/10\/Copa-de-fresas-con-higos.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Continuamos realizando postres sencillos con presentaci\u00f3n de lujo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>6 higos<\/strong><\/p>\n<p><strong>12 fresas<\/strong><\/p>\n<p><strong>2 bombones<\/strong><\/p>\n<p><strong>Yogurt de avellanas<\/strong><\/p>\n<p><strong>Cristales de az\u00facar azules y amarillos<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Lavamos y troceamos a trocitos aptos para comerlos con una cuchara de postre los higos y las fresas.<\/p>\n<p>Repartimos las frutas entre dos copas y cubrimos con el yogurt de avellanas.<\/p>\n<p>Colocamos en el centro de cada copa un bomb\u00f3n.<\/p>\n<p>Decoramos con cristales de az\u00facar de colores.<\/p>\n<p>Guardar en el frigor\u00edfico hasta el momento de servir.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Continuamos realizando postres sencillos con presentaci\u00f3n de lujo. &nbsp; Ingredientes (2 personas): \u00a0 6 higos 12 fresas 2 bombones Yogurt de avellanas Cristales de az\u00facar azules y amarillos \u00a0 Preparaci\u00f3n: \u00a0 Lavamos y troceamos a trocitos aptos para comerlos con una cuchara de postre los higos y las fresas. Repartimos las frutas entre dos copas [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-4826","post","type-post","status-publish","format-standard","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4826"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4826\/revisions"}],"predecessor-version":[{"id":4828,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4826\/revisions\/4828"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}