{"id":4800,"date":"2017-10-24T06:57:00","date_gmt":"2017-10-24T04:57:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4800"},"modified":"2017-10-24T06:57:00","modified_gmt":"2017-10-24T04:57:00","slug":"rollito-de-marisco","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2017\/10\/24\/rollito-de-marisco\/","title":{"rendered":"Rollito de marisco"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4801\" src=\"\/\/blogs.elcorreo.com\/jorbasmar\/wp-content\/uploads\/sites\/153\/2017\/10\/Rollito-de-marisco-300x200.jpg\" alt=\"rollito-de-marisco\" width=\"300\" height=\"200\" srcset=\"\/wp-content\/uploads\/\/sites\/153\/2017\/10\/Rollito-de-marisco-300x200.jpg 300w, \/wp-content\/uploads\/\/sites\/153\/2017\/10\/Rollito-de-marisco.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Hoy os presento una estupenda cena, se trata de una variante de la ensaladilla rusa, pero en lugar de hacerla con verduras, est\u00e1 realizada con gambas cocidas y surimi, envueltas en una tortilla francesa cuadrada.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>3 huevos<\/strong><\/p>\n<p><strong>20 gambas cocidas<\/strong><\/p>\n<p><strong>4 barritas de surimi (palitos de cangrejo)<\/strong><\/p>\n<p><strong>2 banderillas<\/strong><\/p>\n<p><strong>Mix de r\u00facula y can\u00f3nigos<\/strong><\/p>\n<p><strong>4 aceitunas rellenas<\/strong><\/p>\n<p><strong>1 latita de pimientos rojos en conserva<\/strong><\/p>\n<p><strong>Mayonesa<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Comenzamos por realizar dos tortillas francesas de un huevo, a poder ser con la ayuda de una sart\u00e9n cuadrada peque\u00f1ita (si no la tenemos, las realizamos redondas y tambi\u00e9n sirven).<\/p>\n<p>Con la ayuda de un molde de silicona con forma de estrella, realizaremos los huevos cocidos (al vapor), con forma de estrella, o la forma que deseemos.<\/p>\n<p>Aceitamos el molde de silicona (podemos realizar m\u00e1s huevos para pr\u00f3ximas recetas por el mismo precio), cascamos el huevo en el molde y lo salamos.<\/p>\n<p>Colocamos el molde de silicona en una cocedora al vapor y dejamos cocer hasta que cuaje el huevo.<\/p>\n<p>Dejamos enfriar y desmoldamos.<\/p>\n<p>Pelamos las gambas cocidas y las troceamos.<\/p>\n<p>Troceamos tambi\u00e9n las varitas de surimi.<\/p>\n<p>Mezclamos en un recipiente las gambas troceadas y el surimi.<\/p>\n<p>A\u00f1adimos mayonesa y mezclamos bien.<\/p>\n<p>Troceamos el mix de can\u00f3nigos y r\u00facula, cubriendo el fondo del plato donde serviremos nuestro rollito de marisco.<\/p>\n<p>Sazonamos y aceitamos ambas verduras.<\/p>\n<p>Repartimos las gambas y el surimi mezclados con mayonesa entre ambas tortillas y envolvemos la mezcla con las tortillas de forma que la uni\u00f3n de la tortilla quede oculta en el fondo del plato.<\/p>\n<p>Cortamos por la mitad nuestro huevo cocido con forma de estrella, de forma que mantengamos la forma de estrella (v\u00e9ase la fotograf\u00eda).<\/p>\n<p>Colocamos la estrella de huevo cocido en un lado de cada rollito y en el otro lado una banderilla picantita.<\/p>\n<p>Decoramos con las aceitunas rellenas partidas en dos y tiritas del pimiento rojo de lata.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy os presento una estupenda cena, se trata de una variante de la ensaladilla rusa, pero en lugar de hacerla con verduras, est\u00e1 realizada con gambas cocidas y surimi, envueltas en una tortilla francesa cuadrada. &nbsp; Ingredientes (2 personas): \u00a0 3 huevos 20 gambas cocidas 4 barritas de surimi (palitos de cangrejo) 2 banderillas Mix [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-4800","post","type-post","status-publish","format-standard","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4800"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4800\/revisions"}],"predecessor-version":[{"id":4802,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4800\/revisions\/4802"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}