{"id":4791,"date":"2017-10-20T08:20:42","date_gmt":"2017-10-20T06:20:42","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4791"},"modified":"2017-10-20T08:20:42","modified_gmt":"2017-10-20T06:20:42","slug":"vasitos-de-pepino-con-anchoas-y-mayonesa","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2017\/10\/20\/vasitos-de-pepino-con-anchoas-y-mayonesa\/","title":{"rendered":"Vasitos de pepino con anchoas y mayonesa"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4792\" src=\"\/\/blogs.elcorreo.com\/jorbasmar\/wp-content\/uploads\/sites\/153\/2017\/10\/Vasitos-de-pepino-con-anchoas-y-mayonesa-300x200.jpg\" alt=\"vasitos-de-pepino-con-anchoas-y-mayonesa\" width=\"300\" height=\"200\" srcset=\"\/wp-content\/uploads\/\/sites\/153\/2017\/10\/Vasitos-de-pepino-con-anchoas-y-mayonesa-300x200.jpg 300w, \/wp-content\/uploads\/\/sites\/153\/2017\/10\/Vasitos-de-pepino-con-anchoas-y-mayonesa.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>En esta receta aprenderemos a realizar unos espectaculares vasitos cuadrados con un simple pepino.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (4 vasitos):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>1 pepino<\/strong><\/p>\n<p><strong>1 lata de anchoas en aceite<\/strong><\/p>\n<p><strong>Mayonesa<\/strong><\/p>\n<p><strong>Mix de r\u00facula y can\u00f3nigos (para decorar)<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Comenzamos por lavar y convertir el pepino en un rect\u00e1ngulo, cort\u00e1ndole las puntas y una loncha finita de su piel, procurando que le quede algo de piel para que haga bonito en cada una de las cuatro caras con las que formaremos dicho rect\u00e1ngulo.<\/p>\n<p>Cortamos el rect\u00e1ngulo de pepino en forma de daditos y con ayuda de un saca bolas, vaciamos su interior con cuidado de no romperlo.<\/p>\n<p>Troceamos unos ocho lomos de anchoas y los mezclamos con una cucharada de mayonesa.<\/p>\n<p>Rellenamos con esta mezcla nuestros vasitos de pepino.<\/p>\n<p>Decoramos el plato donde serviremos nuestros vasitos de pepino con unas hojas de r\u00facula y can\u00f3nigos troceados y mezclados.<\/p>\n<p>Salamos y aceitamos la verdura y colocamos los vasitos sobre ellas.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En esta receta aprenderemos a realizar unos espectaculares vasitos cuadrados con un simple pepino. &nbsp; Ingredientes (4 vasitos): \u00a0 1 pepino 1 lata de anchoas en aceite Mayonesa Mix de r\u00facula y can\u00f3nigos (para decorar) Aceite de oliva Sal \u00a0 Preparaci\u00f3n: \u00a0 Comenzamos por lavar y convertir el pepino en un rect\u00e1ngulo, cort\u00e1ndole las puntas [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-4791","post","type-post","status-publish","format-standard","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4791"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4791\/revisions"}],"predecessor-version":[{"id":4793,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4791\/revisions\/4793"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}