{"id":4309,"date":"2017-01-10T07:05:35","date_gmt":"2017-01-10T06:05:35","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4309"},"modified":"2017-01-10T07:05:35","modified_gmt":"2017-01-10T06:05:35","slug":"bocadillo-de-jamon-cocido-con-queso","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2017\/01\/10\/bocadillo-de-jamon-cocido-con-queso\/","title":{"rendered":"Bocadillo de jam\u00f3n cocido con queso"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/2.bp.blogspot.com\/-Saj7HPMjmYQ\/WHR2yjbXD3I\/AAAAAAAAF58\/dy62GKc6fyM3940PdTtCOEkBeAE55k4ZwCLcB\/s320\/Bocadillo%2Bde%2Bjam%25C3%25B3n%2Bcocido%2Bcon%2Bqueso.JPG\" alt=\"\" width=\"320\" height=\"213\" \/><\/p>\n<p>El otro d\u00eda, no pudimos sobrevivir a la tentaci\u00f3n de comprar un jam\u00f3n asado en una conocida gran superficie, el cual est\u00e1 delicioso, pero a ver c\u00f3mo nos comemos todo ese trozo de carne cocida entre dos personas\u2026<\/p>\n<p>La otra noche se nos ocurri\u00f3 realizar un bocadillo de jam\u00f3n cocido y qued\u00f3 delicioso.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>1 barra de pan<\/strong><\/p>\n<p><strong>Lonchas de jam\u00f3n asado<\/strong><\/p>\n<p><strong>3 tranchetes de queso<\/strong><\/p>\n<p><strong>1 tomate<\/strong><\/p>\n<p><strong>Perejil<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Para realizar este bocadillo, en primer lugar prepararemos una salsa de tomate.<\/p>\n<p>Lavamos, troceamos e introducimos un tomate maduro en el vaso de la batidora, le a\u00f1adimos perejil fresco, sal, aceite de oliva y trituramos.<\/p>\n<p>Cortamos por la mitad la barra de pan y abrimos esta longitudinalmente.<\/p>\n<p>Untamos la parte interior de ambos bocadillos con la salsa preparada.<\/p>\n<p>Colocamos en dos mitades del pan las lonchas de jam\u00f3n cocido y sobre estas colocamos los tranchetes partidos por la mitad, colocando tres mitades en cada bocadillo.<\/p>\n<p>Cubrimos con el pan restante y partimos cada bocadillo en dos, para posteriormente comerlo con mayor comodidad.<\/p>\n<p>Horneamos a 150\u00ba a partir de horno fr\u00edo unos 7-10 minutos.<\/p>\n<p>Comer templadito y con un delicioso pan crujiente.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El otro d\u00eda, no pudimos sobrevivir a la tentaci\u00f3n de comprar un jam\u00f3n asado en una conocida gran superficie, el cual est\u00e1 delicioso, pero a ver c\u00f3mo nos comemos todo ese trozo de carne cocida entre dos personas\u2026 La otra noche se nos ocurri\u00f3 realizar un bocadillo de jam\u00f3n cocido y qued\u00f3 delicioso. &nbsp; Ingredientes [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4309","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4309"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4309\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}