{"id":4280,"date":"2016-12-15T07:16:17","date_gmt":"2016-12-15T06:16:17","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4280"},"modified":"2016-12-15T07:16:17","modified_gmt":"2016-12-15T06:16:17","slug":"gambas-flambeadas-con-mejillones","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/12\/15\/gambas-flambeadas-con-mejillones\/","title":{"rendered":"Gambas flambeadas con mejillones"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/1.bp.blogspot.com\/-8HvIRkeVcjM\/WFIxlqtfq_I\/AAAAAAAAFl4\/rLLhIHMLz200EL3Wxn5vg1S1_cVl1gNbQCLcB\/s320\/Gambas%2Bflambeadas%2Bcon%2Bmejillones.JPG\" alt=\"\" width=\"320\" height=\"213\" \/><\/p>\n<p>El otro d\u00eda, nos sobraron unos mejillones cocidos de otra receta, se me ocurri\u00f3 que podr\u00edan quedar muy ricos acompa\u00f1ados de unas gambas flambeadas con brandy, adem\u00e1s as\u00ed tambi\u00e9n aprovechaba los restos de un all i oli casero.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>14 gambas grandes congeladas<\/strong><\/p>\n<p><strong>14 mejillones cocidos<\/strong><\/p>\n<p><strong>Salsa all i oli (tambi\u00e9n se vende en supermercados)<\/strong><\/p>\n<p><strong>1 copa de brandy<\/strong><\/p>\n<p><strong>Sal en escamas<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Ajo y perejil seco<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p>Como tanto el all i oli, como los mejillones son sobras, solo tendremos que desechar una de las valvas de los mejillones y con la ayuda de una cucharilla de caf\u00e9, colocar el all i oli en los mejillones.<\/p>\n<p>En una sart\u00e9n grande con un chorrito de aceite de oliva, una vez se caliente, colocamos las gambas previamente descongeladas.<\/p>\n<p>Salamos abundantemente con sal en escamas y un preparado de perejil y ajo seco.<\/p>\n<p>Dejamos hasta que cambien de color las gambas y les damos la vuelta.<\/p>\n<p>Regamos generosamente con el brandy y le prendemos fuego.<\/p>\n<p>Cuando se queme el alcohol servimos alternando una gamba y un mejill\u00f3n, como pod\u00e9is apreciar en la foto.<\/p>\n<p>Buen provecho.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El otro d\u00eda, nos sobraron unos mejillones cocidos de otra receta, se me ocurri\u00f3 que podr\u00edan quedar muy ricos acompa\u00f1ados de unas gambas flambeadas con brandy, adem\u00e1s as\u00ed tambi\u00e9n aprovechaba los restos de un all i oli casero. &nbsp; Ingredientes (2 personas): \u00a0 14 gambas grandes congeladas 14 mejillones cocidos Salsa all i oli (tambi\u00e9n [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4280","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4280"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4280\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}