{"id":4255,"date":"2016-11-21T07:36:04","date_gmt":"2016-11-21T06:36:04","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4255"},"modified":"2016-11-21T07:36:04","modified_gmt":"2016-11-21T06:36:04","slug":"rodajas-de-calabacin-relleno-de-carne-y-beicon","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/11\/21\/rodajas-de-calabacin-relleno-de-carne-y-beicon\/","title":{"rendered":"Rodajas de calabacin relleno de carne y beicon"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/1.bp.blogspot.com\/-zyMXxRJCdl0\/WDKUU17V2uI\/AAAAAAAAFZY\/Bj3rgje_i0wCRvgqzwjEmTVnsCmqcZcCQCLcB\/s320\/Rodajas%2Bde%2Bcalabacin%2Brelleno%2Bde%2Bcarne%2By%2Bbeicon.JPG\" alt=\"\" width=\"320\" height=\"239\" \/><\/p>\n<p>Hoy os presento una forma espectacular de comer calabac\u00edn para los comensales poco adictos a las verduras.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>1 calabac\u00edn muy grande<\/strong><\/p>\n<p><strong>4 lonchas de beicon ahumado<\/strong><\/p>\n<p><strong>2 filetes de cerdo<\/strong><\/p>\n<p><strong>4 huevos<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Comenzamos por cortar el calabac\u00edn en rodajas de 3 o 4 dedos de grosor.<\/p>\n<p>Cocemos el calabac\u00edn al vapor, as\u00ed podemos controlar con facilidad el grado de cocci\u00f3n sin que se nos desmonte o nos quede duro y adem\u00e1s lo cocinamos de una forma muy sana.<\/p>\n<p>Podemos aprovechar para cocer m\u00e1s cosas (si tenemos espacio) para futuras recetas.<\/p>\n<p>Una vez cocido el calabac\u00edn lo dejamos enfriar para trabajar con comodidad.<\/p>\n<p>Mientras se nos enfr\u00eda el calabac\u00edn, asamos a la plancha con un poco de aceite el beicon y los filetes de cerdo.<\/p>\n<p>Vaciamos el interior de cuatro de las rodajas de calabac\u00edn, con la ayuda de un saca bolas (reservamos para futuras recetas las rodajas que nos sobren y el calabac\u00edn que saquemos que las rodajas que utilizaremos).<\/p>\n<p>Salamos abundantemente las rodajas de calabac\u00edn vaciadas y colocamos una loncha de beicon alrededor de la parte interior de cada rodaja.<\/p>\n<p>Cortamos a taquitos ambos filetes de cerdo y los repartimos entre las cuatro rodajas de calabac\u00edn que contienen el tocino.<\/p>\n<p>Colocamos un huevo crudo cubriendo cada rodaja de calabac\u00edn y salamos de nuevo.<\/p>\n<p>Horneamos con calor abajo a 150\u00ba a partir de horno fr\u00edo hasta que cuaje la clara (unos 20-25 minutos).<\/p>\n<p>Nota:<\/p>\n<p>Se pueden cubrir los huevos con queso rallado y gratinar unos 5 minutos antes de servir, pero yo no le puse, porque a mi mujer no le gusta el queso gratinado.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy os presento una forma espectacular de comer calabac\u00edn para los comensales poco adictos a las verduras. &nbsp; Ingredientes (2 personas): \u00a0 1 calabac\u00edn muy grande 4 lonchas de beicon ahumado 2 filetes de cerdo 4 huevos Aceite de oliva Sal Preparaci\u00f3n: \u00a0 Comenzamos por cortar el calabac\u00edn en rodajas de 3 o 4 dedos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4255","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4255"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4255\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}