{"id":4242,"date":"2016-11-08T06:36:29","date_gmt":"2016-11-08T05:36:29","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4242"},"modified":"2016-11-08T06:36:29","modified_gmt":"2016-11-08T05:36:29","slug":"hinduismo","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/11\/08\/hinduismo\/","title":{"rendered":"Hinduismo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/4.bp.blogspot.com\/-hUWfMZ2mQpI\/WCFit1QwUvI\/AAAAAAAAFU4\/sGd1Q6JCkzAjSRB-3nT5Fz63qe14WgeiACLcB\/s320\/Hinduismo.jpg\" alt=\"\" width=\"320\" height=\"226\" \/><\/p>\n<p>El hinduismo, es la tercera tradici\u00f3n religiosa m\u00e1s extendida del planeta, solo superada por el <a href=\"http:\/\/jorbasmar.blogspot.com.es\/2016\/08\/cristianismo.html\" rel=\"external nofollow\">cristianismo<\/a> y el <a href=\"http:\/\/jorbasmar.blogspot.com.es\/2016\/07\/islamismo.html\" rel=\"external nofollow\">islamismo<\/a>, principalmente difundida en la India\u00a0 y en Nepal.<\/p>\n<p>La India fue la cuna del hinduismo y a pesar de tener m\u00e1s de mil millones de fieles, solo es la religi\u00f3n mayoritaria en la India, Nepal, Rep\u00fablica de Mauricio y Bali, aunque tambi\u00e9n hay muchos adeptos hinduistas en Afganist\u00e1n, <a href=\"http:\/\/jorbasmar.blogspot.com.es\/2014\/08\/el-reino-de-butan.html\" rel=\"external nofollow\">But\u00e1n<\/a>, Birmania, Camboya, Indonesia, Malasia, Sri Lanka, Tailandia, Gran Breta\u00f1a, Estados Unidos, Panam\u00e1 y Trinidad y Tobago.<\/p>\n<p>Realmente no existe un fundador del hinduismo, puesto que el hinduismo no es una sola religi\u00f3n, consiste en un conjunto de religiones a las cuales err\u00f3neamente se les aplica el mismo nombre.<\/p>\n<p>El hinduismo es un conjunto de creencias metaf\u00edsicas, religiosas, cultos, costumbres y rituales, las cuales forman una tradici\u00f3n que no posee \u00f3rdenes sacerdotales que inculquen un dogma \u00fanico, ni posee una organizaci\u00f3n central.<\/p>\n<p>Realmente el hinduismo consiste en un conjunto de creencias de diferentes pueblos, unidas a las tra\u00eddas por los arios (persas), que se establecieron en la cuenca del rio Ganges, las cuales fueron escritas en forma de revelaciones en escritos v\u00e9dicos y libros sagrados hinduistas.<\/p>\n<p>La tradici\u00f3n religiosa hinduista es llamada sanatana dharma (religi\u00f3n eterna), a causa de la creencia de que dicha tradici\u00f3n, ni tiene principio, ni tampoco tiene fin.<\/p>\n<p>Los hinduistas afirman que el hinduismo posee m\u00e1s de 5.000 a\u00f1os de antig\u00fcedad, siendo la tradici\u00f3n religiosa m\u00e1s antigua del mundo.<\/p>\n<p>Los escritos hinduistas son de los m\u00e1s antiguos conservados y est\u00e1n datados entre los 1.400 y 1.500 a\u00f1os antes de Cristo.<\/p>\n<p>Dentro de la cultura hinduista existe el te\u00edsmo (creencia en deidades o en un creador del universo que est\u00e1 comprometido con su mantenimiento y gobierno), el de\u00edsmo (filosof\u00eda que admite el conocimiento y la existencia de Dios a trav\u00e9s de la raz\u00f3n y la experiencia personal), el polite\u00edsmo (existencia de m\u00faltiples dioses o deidades, organizados en una jerarqu\u00eda o pante\u00f3n), el pante\u00edsmo (doctrina filos\u00f3fica seg\u00fan la cual el universo, la naturaleza y Dios son equivalentes), el agnosticismo (doctrina filos\u00f3fica que ni cree, ni deja de creer en la existencia de Dios), y el ate\u00edsmo (doctrina que niega la existencia de Dios).<\/p>\n<p>Los hinduistas visnu\u00edstas adoran al dios Visn\u00fa, creyendo que su avatar es Krisn\u00e1.<\/p>\n<p>Las hinduistas krisna\u00edstas adoran al dios Krisn\u00e1 y creen que su avatar es Visn\u00fa.<\/p>\n<p>La doctrina vedanta afirma que Brahman, es la forma original de Dios, siendo todos los dem\u00e1s dioses y seres del universo su expresi\u00f3n, siendo Brahman considerado el principio del universo.<\/p>\n<p>Los shiva\u00edstas aseguran que Shiva es el \u00fanico dios, negando la importancia de Brahm\u00e1 y Visn\u00fa.<\/p>\n<p>La doctrina samkhia de Kapil\u00e1 consiste en una filosof\u00eda atea.<\/p>\n<p>Al igual que ha diversidad de ramas en la filosof\u00eda hinduista, sus creencias tambi\u00e9n son diferentes, aunque b\u00e1sicamente los hinduista opinan que detr\u00e1s del universo visible (maia), un universo con ciclos sucesivos de creaci\u00f3n y destrucci\u00f3n, el principio que sostiene el universo es Brahman y el mayor logro para todos los hinduistas es deja el ciclo de reencarnaciones (samsara), regresando al principio divino.<\/p>\n<p>En textos occidentales se hizo popular la triada hinduista (Trimurti), consistente en tres formas de dioses masculinos, Brahm\u00e1, Visn\u00fa y Shiva, aunque generalmente nadie adora el Trimurti.<\/p>\n<p>Entre los textos sagrados hinduistas podemos destacar los siguientes:<\/p>\n<p>Shruti, conjunto de textos revelados, los cuales no pueden ser interpretados y han de ser seguidos al pie de la letra, los cuatro Vedas (Rig-veda, L\u00e1yur-veda, Sama-veda y Atharva-veda) y tambi\u00e9n las Upanishad (meditaciones mistico-filos\u00f3ficas).<\/p>\n<p>Tambi\u00e9n son textos sagrados el Smriti, el Majabh\u00e1rata, el Ramaiana, las 18 Puranas y los textos antiguos sobre \u00e1iur-veda.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Fuentes:<\/strong><\/p>\n<p><a href=\"http:\/\/es.wikipedia.org\/wiki\/Hinduismo\" rel=\"external nofollow\"><strong>http:\/\/es.wikipedia.org\/wiki\/Hinduismo<\/strong><\/a><strong><\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El hinduismo, es la tercera tradici\u00f3n religiosa m\u00e1s extendida del planeta, solo superada por el cristianismo y el islamismo, principalmente difundida en la India\u00a0 y en Nepal. La India fue la cuna del hinduismo y a pesar de tener m\u00e1s de mil millones de fieles, solo es la religi\u00f3n mayoritaria en la India, Nepal, Rep\u00fablica [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4242","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4242"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4242\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}