{"id":4237,"date":"2016-11-04T07:32:20","date_gmt":"2016-11-04T06:32:20","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4237"},"modified":"2016-11-04T07:32:20","modified_gmt":"2016-11-04T06:32:20","slug":"ensalada-con-rollitos-de-jamon-dulce","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/11\/04\/ensalada-con-rollitos-de-jamon-dulce\/","title":{"rendered":"Ensalada con rollitos de jam\u00f3n dulce"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/4.bp.blogspot.com\/-5gF8TdHRwDo\/WBwoz_j9JxI\/AAAAAAAAFPg\/o0cDLKXN5GQEmUu8vYGl23Y58vgJHfNZQCLcB\/s320\/Ensalada%2Bcon%2Brollitos%2Bde%2Bjam%25C3%25B3n%2Bdulce.JPG\" alt=\"\" width=\"320\" height=\"213\" \/><\/p>\n<p>En esta ocasi\u00f3n, os presento una ensalada muy normalita, pero acompa\u00f1ada de unas rebanadas de pan de molde enrolladas con jam\u00f3n dulce.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>2 rebanadas grandes de pan de molde<\/strong><\/p>\n<p><strong>2 lonchas gruesas de jam\u00f3n dulce<\/strong><\/p>\n<p><strong>1 tomate<\/strong><\/p>\n<p><strong>1 pu\u00f1adito de tomates cherrys<\/strong><\/p>\n<p><strong>1 cucharada de encurtidos (pepinillos, cebollitas, aceitunas\u2026)<\/strong><\/p>\n<p><strong>Lechuga<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Vinagre<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>En primer lugar preparamos la salsa para untar el pan de molde, lavando y troceando el tomate, a\u00f1adi\u00e9ndole aceite y sal al gusto, tritur\u00e1ndolo posteriormente con la batidora.<\/p>\n<p>Con la ayuda del rulo de estirar la masa, aplastamos ambas rebanadas de pan de molde, hasta pr\u00e1cticamente doblar su tama\u00f1o.<\/p>\n<p>Untamos una cara de ambas rebanadas con la salsa de tomate preparada.<\/p>\n<p>Colocamos cada rebanada sobre un trozo de pl\u00e1stico de cocina y sobre cada rebanada colocamos una loncha de jam\u00f3n dulce y una hoja de lechuga.<\/p>\n<p>Enrollamos la rebanada sobre s\u00ed misma, formando una especie de canel\u00f3n y mantenemos su forma con ayuda del pl\u00e1stico.<\/p>\n<p>Guardamos en la nevera un par de horas, para que el pan memorice su nueva forma (yo lo dej\u00e9 poco rato por eso no ha quedado muy bien).<\/p>\n<p>Pasadas ese par de horas o m\u00e1s, picamos finas unas hojas de lechuga, partimos en dos los tomates cherrys y a\u00f1adimos los encurtidos a dos bandejas individuales.<\/p>\n<p>Quitamos los pl\u00e1sticos a nuestros rollitos de pan de molde y cortamos cada rollito en cuatro rodajas, colocando una de ellas en cada esquina de nuestra bandeja.<\/p>\n<p>Aderezamos la ensalada con sal, aceite y vinagre.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En esta ocasi\u00f3n, os presento una ensalada muy normalita, pero acompa\u00f1ada de unas rebanadas de pan de molde enrolladas con jam\u00f3n dulce. &nbsp; Ingredientes (2 personas): \u00a0 2 rebanadas grandes de pan de molde 2 lonchas gruesas de jam\u00f3n dulce 1 tomate 1 pu\u00f1adito de tomates cherrys 1 cucharada de encurtidos (pepinillos, cebollitas, aceitunas\u2026) Lechuga [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4237","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4237"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4237\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}