{"id":4229,"date":"2016-10-27T06:55:26","date_gmt":"2016-10-27T05:55:26","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4229"},"modified":"2016-10-27T06:55:26","modified_gmt":"2016-10-27T05:55:26","slug":"tartar-de-arroz-pimientos-y-uvas","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/10\/27\/tartar-de-arroz-pimientos-y-uvas\/","title":{"rendered":"Tartar de arroz, pimientos y uvas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/3.bp.blogspot.com\/-kWmY3OZ-h7c\/WBGUwvk8Z9I\/AAAAAAAAFCI\/yhpG1lGHX6wa2h24kmYV_0-mtLc8xGjDACLcB\/s320\/Tartar%2Bde%2Barroz%252C%2Bpimientos%2By%2Buvas.JPG\" alt=\"\" width=\"320\" height=\"239\" \/><\/p>\n<p>En esta ocasi\u00f3n os presento una comida barata, sencilla y espectacular, que combina lo caliente del arroz cocido en agua de mar, con una ensalada fresca, servida en el mismo plato.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>2 pu\u00f1aditos de arroz<\/strong><\/p>\n<p><strong>2 pimientos verdes<\/strong><\/p>\n<p><strong>2 tomates<\/strong><\/p>\n<p><strong>8 uvas negras<\/strong><\/p>\n<p><strong>2 uvas blancas<\/strong><\/p>\n<p><strong>4 cucharadas de encurtidos variados (pepinillos, cebolletas, aceitunas, etc)<\/strong><\/p>\n<p><strong>1 cucharadita de colorante alimentario (azafr\u00e1n)<\/strong><\/p>\n<p><strong>Jengibre<\/strong><\/p>\n<p><strong>Agua de mar (se vende en supermercados, sirve agua con sal)<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Vinagre<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Para realizar esta receta, en primer lugar coceremos el arroz en abundante agua de mar (mezclar al 50% con agua del grifo para que no quede salado), a\u00f1adimos el jengibre y el colorante.<\/p>\n<p>Mientras cocemos el arroz, lavamos, desechamos las semillas y fre\u00edmos los pimientos.<\/p>\n<p>Cuando tengamos el arroz tierno lo escurrimos con la ayuda de un colador.<\/p>\n<p>Solo nos resta aceitar dos moldes de aro y rellenarlos hasta la mitad con el arroz, repartimos los pimientos fritos sobre el arroz y terminamos de llenar los aros con el arroz que nos resta.<\/p>\n<p>Decoramos el arroz con las uvas.<\/p>\n<p>Si se nos enfr\u00eda el arroz, podemos calentarlo al horno unos 15 minutos a 160\u00ba antes de servir.<\/p>\n<p>Momentos antes de servir, desmoldamos el arroz y colocamos alrededor del tartar, lechuga picada.<\/p>\n<p>Repartimos entre los dos platos ambos tomates troceados y los encurtidos.<\/p>\n<p>Rociamos con aceite y vinagre.<\/p>\n<p>No puse sal puesto que el arroz lleva la sal del agua marina.<\/p>\n<p>Servir inmediatamente, antes que el arroz se enfr\u00ede.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En esta ocasi\u00f3n os presento una comida barata, sencilla y espectacular, que combina lo caliente del arroz cocido en agua de mar, con una ensalada fresca, servida en el mismo plato. &nbsp; Ingredientes (2 personas): \u00a0 2 pu\u00f1aditos de arroz 2 pimientos verdes 2 tomates 8 uvas negras 2 uvas blancas 4 cucharadas de encurtidos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4229","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4229"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4229\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}