{"id":4213,"date":"2016-10-13T05:57:00","date_gmt":"2016-10-13T04:57:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4213"},"modified":"2016-10-13T05:57:00","modified_gmt":"2016-10-13T04:57:00","slug":"pechuga-de-pollo-picante-cocida","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/10\/13\/pechuga-de-pollo-picante-cocida\/","title":{"rendered":"Pechuga de pollo picante cocida"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/2.bp.blogspot.com\/-qIXg2oAicAw\/V_8R_z66XhI\/AAAAAAAAE4U\/LSLBzOiKjw4zau0NNFh05yXfHpSlMghIQCLcB\/s320\/Pechuga%2Bde%2Bpollo%2Bpicante%2Bcocida.JPG\" alt=\"\" width=\"239\" height=\"320\" \/><\/p>\n<p>Aunque en casa, somos mucho m\u00e1s amigos de los fritos que de los cocidos, nos hemos acostumbrado en casa a comer las pechugas de pollo, deshuesadas y hervidas.<\/p>\n<p>La verdad, es que de esta forma se come sano, f\u00e1cil, con poco trabajo y queda riqu\u00edsima la pechuga.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>1 pechuga de pollo<\/strong><\/p>\n<p><strong>\u00bd barra de pan<\/strong><\/p>\n<p><strong>1 tomate maduro<\/strong><\/p>\n<p><strong>Piment\u00f3n picante (puede ser dulce)<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>La preparaci\u00f3n de esta receta es muy simple, pero como pod\u00e9is observar en la foto la presentaci\u00f3n es espectacular.<\/p>\n<p>En primer lugar aceitamos un papel de aluminio (tambi\u00e9n sirve el pl\u00e1stico de cocina) y colocamos nuestra pechuga de pollo deshuesada sobre \u00e9l.<\/p>\n<p>Salamos y embadurnamos abundantemente la pechuga con el piment\u00f3n picante, rociamos con un poquito de aceite m\u00e1s y envolvemos con el papel aluminio.<\/p>\n<p>Cocemos al vapor a fuego medio nuestra pechuga, alrededor de 30 minutos (pod\u00e9is aprovechar para hacer m\u00e1s pechugas o cocer lo que dese\u00e9is al vapor por el mismo trabajo).<\/p>\n<p>Dejamos enfriar la pechuga.<\/p>\n<p>Preparamos mi salsa de tomate, troceamos el tomate, le a\u00f1adimos sal y un generoso chorro de aceite, posteriormente lo trituramos con la batidora.<\/p>\n<p>Cortamos la barra de pan a rebanadas.<\/p>\n<p>Untamos las rebanadas de pan con la salsa de tomate.<\/p>\n<p>Sobre cada rebanada de pan colocamos una loncha de nuestra pechuga.<\/p>\n<p>En esta ocasi\u00f3n lo hemos servido en frio que queda delicioso, pero si introducimos el pan con la pechuga en el horno unos 15-20 minutos antes de servir (a partir de horno fr\u00edo a unos 150\u00ba), tambi\u00e9n queda de f\u00e1bula.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Aunque en casa, somos mucho m\u00e1s amigos de los fritos que de los cocidos, nos hemos acostumbrado en casa a comer las pechugas de pollo, deshuesadas y hervidas. La verdad, es que de esta forma se come sano, f\u00e1cil, con poco trabajo y queda riqu\u00edsima la pechuga. &nbsp; Ingredientes (2 personas): \u00a0 1 pechuga de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4213","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4213"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4213\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}