{"id":4202,"date":"2016-10-01T07:04:32","date_gmt":"2016-10-01T06:04:32","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4202"},"modified":"2016-10-01T07:04:32","modified_gmt":"2016-10-01T06:04:32","slug":"ensalada-de-higos-y-granada","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/10\/01\/ensalada-de-higos-y-granada\/","title":{"rendered":"Ensalada de higos y granada"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/2.bp.blogspot.com\/-bTTC61TzSDM\/V-9O-dxxHpI\/AAAAAAAAEz8\/eO3WF2M0z3sPEw2zmz131nYV1kOG7mOLwCLcB\/s320\/Ensalada%2Bde%2Bhigos%2By%2Bgranada.JPG\" alt=\"\" width=\"320\" height=\"213\" \/><\/p>\n<p>En esta ocasi\u00f3n he querido realizar una ensalada muy diferente, la cual sorprender\u00e1 cualquier mesa, pero la verdad es que se trata de una ensalada deliciosa.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>1 pu\u00f1adito de <\/strong><a href=\"http:\/\/jorbasmar.blogspot.com.es\/2015\/12\/canonigos.html\" rel=\"external nofollow\"><strong>can\u00f3nigos<\/strong><\/a><strong><\/strong><\/p>\n<p><strong>4 higos<\/strong><\/p>\n<p><strong>1 queso fresco peque\u00f1o<\/strong><\/p>\n<p><strong>1 huevo cocido<\/strong><\/p>\n<p><strong>Granada (una cuarta parte de los granos de una granada)<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>Aceite<\/strong><\/p>\n<p><strong>Vinagre<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Colocamos sobre la base del plato donde serviremos la ensalada una cama de <a href=\"http:\/\/jorbasmar.blogspot.com.es\/2015\/12\/canonigos.html\" rel=\"external nofollow\">can\u00f3nigos<\/a>.<\/p>\n<p>Lavamos y troceamos longitudinalmente los higos, coloc\u00e1ndolos en los bordes del plato.<\/p>\n<p>En el centro del plato colocamos el queso troceado y el huevo partido en dos.<\/p>\n<p>Decoramos con los granos de granada.<\/p>\n<p>Rociamos con aceite, vinagre y sal.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En esta ocasi\u00f3n he querido realizar una ensalada muy diferente, la cual sorprender\u00e1 cualquier mesa, pero la verdad es que se trata de una ensalada deliciosa. &nbsp; Ingredientes (2 personas): \u00a0 1 pu\u00f1adito de can\u00f3nigos 4 higos 1 queso fresco peque\u00f1o 1 huevo cocido Granada (una cuarta parte de los granos de una granada) Sal [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4202","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4202"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4202\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}