{"id":4200,"date":"2016-09-30T06:46:54","date_gmt":"2016-09-30T05:46:54","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4200"},"modified":"2016-09-30T06:46:54","modified_gmt":"2016-09-30T05:46:54","slug":"triangulos-de-tostadas-de-jamon-dulce-con-mini-hamburguesas","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/09\/30\/triangulos-de-tostadas-de-jamon-dulce-con-mini-hamburguesas\/","title":{"rendered":"Triangulos de tostadas de jam\u00f3n dulce con mini hamburguesas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/4.bp.blogspot.com\/-iHQ9z_tAEaQ\/V-30xeffR3I\/AAAAAAAAEzI\/jhxuxiiwQxoV-kfwvLbis6RDOMoJ9VYdQCLcB\/s320\/Triangulos%2Bde%2Btostadas%2Bde%2Bjam%25C3%25B3n%2Bdulce%2Bcon%2Bmini%2Bhamburguesas.JPG\" alt=\"\" width=\"320\" height=\"239\" \/><\/p>\n<p>Seguimos preparando cenas fr\u00edas, espectaculares y con poco trabajo.<\/p>\n<p>En esta ocasi\u00f3n combinamos diferentes panes con jam\u00f3n cocido y jam\u00f3n salado.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>4 rebanadas de pan de molde grandes<\/strong><\/p>\n<p><strong>4 panecillos de mini hamburguesas<\/strong><\/p>\n<p><strong>2 lonchas de jam\u00f3n cocido<\/strong><\/p>\n<p><strong>Jam\u00f3n salado cortado a taquitos<\/strong><\/p>\n<p><strong>1 tomate<\/strong><\/p>\n<p><strong>Lechuga<\/strong><\/p>\n<p><strong>Mayonesa<\/strong><\/p>\n<p><strong>Salsa Perrins<\/strong><\/p>\n<p><strong>Salsa de soja<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>En primer lugar prepararemos ambas salsas, mientras tostamos el pan de molde en una tostadora.<\/p>\n<p>Lavamos y troceamos el tomate y lo trituramos con la batidora a\u00f1adi\u00e9ndole aceite y sal al gusto (esta salsa es para el jam\u00f3n salado, recordad que ya tiene sal).<\/p>\n<p>A continuaci\u00f3n colocamos 2 o 3 cucharadas soperas de mayonesa en un recipiente y la mezclamos bien con salsa de soja y salsa Perrins al gusto.<\/p>\n<p>Una vez listas ambas salsas y tostado el pan de molde, embadurnamos bien de la salsa de mayonesa y soja un de las caras de las cuatro rebanadas de pan de molde.<\/p>\n<p>Colocamos una hoja de lechuga sobre dos de las rebanadas por la parte untada de mayonesa, cubrimos la lechuga con el jam\u00f3n dulce y este con m\u00e1s lechuga.<\/p>\n<p>Cubrimos la \u00faltima capa de lechuga con las rebanadas de pan de molde sobrantes.<\/p>\n<p>Hacemos en cada s\u00e1ndwich dos cortes en diagonal formando con cada uno cuatro tri\u00e1ngulos, as\u00ed quedara distinto y muy f\u00e1cil de comer para nuestros comensales, sin que a nadie se le desmonte.<\/p>\n<p>Abrimos los mini panecillos de hamburguesa, los untamos con la salsa de tomate, le colocamos taquitos de jam\u00f3n salado y colocamos en el plato donde serviremos.<\/p>\n<p>Recomiendo acompa\u00f1ar de una ensalada.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Seguimos preparando cenas fr\u00edas, espectaculares y con poco trabajo. En esta ocasi\u00f3n combinamos diferentes panes con jam\u00f3n cocido y jam\u00f3n salado. &nbsp; Ingredientes (2 personas): \u00a0 4 rebanadas de pan de molde grandes 4 panecillos de mini hamburguesas 2 lonchas de jam\u00f3n cocido Jam\u00f3n salado cortado a taquitos 1 tomate Lechuga Mayonesa Salsa Perrins Salsa [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4200","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4200"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4200\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}