{"id":4199,"date":"2016-09-29T06:20:56","date_gmt":"2016-09-29T05:20:56","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4199"},"modified":"2016-09-29T06:20:56","modified_gmt":"2016-09-29T05:20:56","slug":"ensalada-de-verduras-y-boquerones","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/09\/29\/ensalada-de-verduras-y-boquerones\/","title":{"rendered":"Ensalada de verduras y boquerones"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/2.bp.blogspot.com\/-BSiqi8a4Pqw\/V-yi8n4Db4I\/AAAAAAAAEyQ\/FMHp2ruH-LIuQQpxYWmFUDeMUYX1aJmjACLcB\/s320\/Ensalada%2Bde%2Bverduras%2By%2Bboquerones.JPG\" alt=\"\" width=\"213\" height=\"320\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Aunque esta temporada est\u00e1n de moda las ensaladas liquidas y las ensaladas de algas en mi cocina (compartida con la mujer, pero cocinando separados o vuelan los cuchillos), el otro d\u00eda vi en el s\u00faper r\u00facula y can\u00f3nigos, como hac\u00eda tiempo que no com\u00edamos dichas verduras, compre un par de bolsitas, as\u00ed que ahora toca sesi\u00f3n de comer verde.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>1 pu\u00f1adito de r\u00facula<\/strong><\/p>\n<p><strong>1 pu\u00f1adito de can\u00f3nigos<\/strong><\/p>\n<p><strong>Unas hojas de lechuga<\/strong><\/p>\n<p><strong>2 tomates peque\u00f1os<\/strong><\/p>\n<p><strong>\u00bd cebolla<\/strong><\/p>\n<p><strong>6 lomos de boquerones en vinagre<\/strong><\/p>\n<p><strong>2 cucharadas de encurtidos (aceitunas, cebollitas, pepinillos\u2026)<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Vinagre<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Nada m\u00e1s f\u00e1cil que preparar esta ensalada.<\/p>\n<p>Colocamos la lechuga troceada, la r\u00facula y los can\u00f3nigos en un escurridor, lav\u00e1ndolos bajo el grifo.<\/p>\n<p>Colocamos toda la verdura en una fuente, una vez escurrida.<\/p>\n<p>Lavamos y troceamos los tomates, a\u00f1adi\u00e9ndolos a la verdura.<\/p>\n<p>Cortamos en pluma la media cebolla, agreg\u00e1ndola a la ensalada.<\/p>\n<p>Unimos a nuestra ensalada los encurtidos.<\/p>\n<p>Ali\u00f1amos con aceite, vinagre y sal, removiendo.<\/p>\n<p>Decoramos con los lomos de boquer\u00f3n.<\/p>\n<p>Guardamos en el frigor\u00edfico hasta el momento de servir.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Aunque esta temporada est\u00e1n de moda las ensaladas liquidas y las ensaladas de algas en mi cocina (compartida con la mujer, pero cocinando separados o vuelan los cuchillos), el otro d\u00eda vi en el s\u00faper r\u00facula y can\u00f3nigos, como hac\u00eda tiempo que no com\u00edamos dichas verduras, compre un par de bolsitas, as\u00ed que ahora [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4199","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4199"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4199\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}