{"id":4180,"date":"2016-09-12T06:28:33","date_gmt":"2016-09-12T05:28:33","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4180"},"modified":"2016-09-12T06:28:33","modified_gmt":"2016-09-12T05:28:33","slug":"macarrones-con-cherrys-y-morcilla","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/09\/12\/macarrones-con-cherrys-y-morcilla\/","title":{"rendered":"Macarrones con cherrys y morcilla"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/1.bp.blogspot.com\/-nJPY7mMh-3E\/V9Y3WR7mfcI\/AAAAAAAAEf4\/CteLLJmVc4o_K5Tm90RToc72wAyNz_vcwCLcB\/s320\/Macarrones%2Bcon%2Bcherrys%2By%2Bmorcilla.JPG\" alt=\"\" width=\"320\" height=\"239\" \/><\/p>\n<p>Hoy os presento una receta diferente, en casa es habitual hacer la pasta con salsa Bolo\u00f1esa, pero, como ten\u00eda muchos tomatitos cherrys de maceta y tambi\u00e9n morcillas perdidas en la nevera\u2026 se me ocurri\u00f3 realizar esta receta que es una forma bien diferente de comer los macarrones.<\/p>\n<p>La idea surge de la web de Cookpad donde \u201cItalia mi amor\u201d nos presenta su receta <a href=\"http:\/\/cookpad.com\/es\/recetas\/642459-espaguetis-integrales-con-alcachofas-y-tomates-cherry\" rel=\"external nofollow\">\u201cEspaguetis integrales con tomates cherrys\u201d.<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Receta de la idea:<\/p>\n<p><a href=\"http:\/\/cookpad.com\/es\/recetas\/642459-espaguetis-integrales-con-alcachofas-y-tomates-cherry\" rel=\"external nofollow\">http:\/\/cookpad.com\/es\/recetas\/642459-espaguetis-integrales-con-alcachofas-y-tomates-cherry<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>2 pu\u00f1aditos de macarrones<\/strong><\/p>\n<p><strong>2 morcillas<\/strong><\/p>\n<p><strong>1 cebolla<\/strong><\/p>\n<p><strong>6 alcachofas baby congeladas<\/strong><\/p>\n<p><strong>2 pu\u00f1ados de tomates cherrys<\/strong><\/p>\n<p><strong>3 ajos<\/strong><\/p>\n<p><strong>1 vasito de vino blanco<\/strong><\/p>\n<p><strong>Mix de hierbas arom\u00e1ticas<\/strong><\/p>\n<p><strong>Aceite<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p>La realizaci\u00f3n de estos macarrones es bien simple.<\/p>\n<p>Llevamos a ebullici\u00f3n en una olla agua con sal y cuando comience a hervir introducimos los macarrones en ella hasta que est\u00e9n a nuestro gusto de cocci\u00f3n o seg\u00fan las instrucciones del fabricante, en mi caso unos 20 minutos.<\/p>\n<p>Mientras se nos cuecen los macarrones, preparamos la salsa.<\/p>\n<p>En una sart\u00e9n colocamos un generoso chorro de aceite y mientras este se calienta, pelamos una cebolla peque\u00f1a y los ajos, troceando la cebolla en juliana y fileteando los ajos, salando para ayudar a sudar la cebolla.<\/p>\n<p>Cuando la cebolla comience a estar tierna, a\u00f1adimos los tomates cherrys enteros (me encanta esa sensaci\u00f3n de explosi\u00f3n en la boca al comerlos), le damos unas vueltas, le a\u00f1adimos un vasito de vino blanco, las alcachofas sin descongelar, tapamos y bajamos el fuego hasta que los tomates y las alcachofas est\u00e9n tiernas.<\/p>\n<p>A\u00f1adimos los macarrones cocidos, previamente escurridos y aderezamos con el mix de especias.<\/p>\n<p>Se remueve, se parten en dos las morcillas, desechando su piel (trat\u00e1ndolas con mimo para que no se nos rompan) y se deja a fuego lento 5-10 minutos para que se integren los sabores.<\/p>\n<p>Servir bien calentito.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy os presento una receta diferente, en casa es habitual hacer la pasta con salsa Bolo\u00f1esa, pero, como ten\u00eda muchos tomatitos cherrys de maceta y tambi\u00e9n morcillas perdidas en la nevera\u2026 se me ocurri\u00f3 realizar esta receta que es una forma bien diferente de comer los macarrones. La idea surge de la web de Cookpad [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4180","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4180"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4180\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}