{"id":4165,"date":"2016-08-26T07:42:35","date_gmt":"2016-08-26T06:42:35","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4165"},"modified":"2016-08-26T07:42:35","modified_gmt":"2016-08-26T06:42:35","slug":"esenios","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/08\/26\/esenios\/","title":{"rendered":"Esenios"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/3.bp.blogspot.com\/-iEE3CpEwpWw\/V7_ixBORR5I\/AAAAAAAAEMQ\/DW9Dga5hgoEKlhDNKNOjlZEYdZc8d_I9wCLcB\/s320\/Esenios.jpg\" alt=\"\" width=\"206\" height=\"320\" \/><\/p>\n<p>Continuamos profundizando, para intentar comprender <a href=\"http:\/\/blogs.elcorreo.com\/jorbasmar\/2011\/12\/25\/buscando-la-verdad-de-la-religion\/\">\u201cla verdad de la religi\u00f3n\u201d<\/a>, en este caso conoceremos este movimiento jud\u00edo, que se cree que se estableci\u00f3 a mediados del siglo II antes de Cristo, tras la revuelta macabea, del cual tenemos documentada su existencia hasta el siglo I, se trata de los esenios.<\/p>\n<p>La revuelta macabea (los macabeos, fueron otro movimiento jud\u00edo de liberaci\u00f3n), sucedi\u00f3 tras en el a\u00f1o 167 antes de Cristo, tras Ant\u00edoco decretar en Judea la prohibici\u00f3n de realizar pr\u00e1cticas religiosas.<\/p>\n<p>Los esenios curaban tanto las enfermedades f\u00edsicas como morales, estudiaban escritos m\u00e9dicos que mostraban las virtudes ocultas de las plantas y los minerales.<\/p>\n<p>Los esenios, se consideraban diferentes del resto de las dem\u00e1s culturas, por la importancia de su vida interna y sus conocimientos ocultos de la naturaleza, los cuales eran desconocidos por el resto de los hombres.<\/p>\n<p>Realmente los esenios no estudiaban una sola religi\u00f3n, estudiaban todas ellas, para obtener de todas ellas los principios cient\u00edficos contenidos en ellas.<\/p>\n<p>Una vez finalizada la revuelta macabea (166-159 antes de Cristo), los esenios no compartieron el resultado final de la revuelta y marcharon al desierto, para preparar el camino al Se\u00f1or, bajo las ordenes del Maestro de la Justicia.<\/p>\n<p>Para pertenecer a la comunidad esenia, era necesario ser ense\u00f1ado y aceptado, tras lo cual deb\u00eda pasar dos a\u00f1os de prueba, antes de ingresar definitivamente en la comunidad, debiendo dedicar la vida al estudio de la Ley, tener humildad y disciplina.<\/p>\n<p>Los esenios estaban obligados a no mentir, todos sus bienes pasaban a formar parte de la comunidad, reparti\u00e9ndose los frutos del trabajo personal seg\u00fan las necesidades de cada esenio, apartando una parte para ayudar a los pobres, viudas, hu\u00e9rfanos, mujeres solteras mayores, desempleados, forasteros y esclavos fugitivos, los cuales eran ayudados sin necesidad de pertenecer a la comunidad, necesitaban ayuda.<\/p>\n<p>En la comunidad esenia no eran aceptadas las mujeres, los hombres practicaban el celibato, aunque seg\u00fan Flavio Josefo, una parte de los esenios permit\u00eda el matrimonio y las normas de Qumr\u00e1n (valle del desierto de Judea, en Cisjordania), permiten casarse, pero bajo la condici\u00f3n de la monogamia (debiendo contraer matrimonio a la edad de 20 a\u00f1os).<\/p>\n<p>El Maestro de Justicia, seg\u00fan los manuscritos del Mar Muerto, hacia el a\u00f1o 150 antes de Cristo, se opuso al Sumo Sacerdote (Jonat\u00e1n Macabeo, hermano de Judas Iscariote), acus\u00e1ndolo de haber abandonado la fidelidad a Dios, marchando el Maestro de Justicia y sus seguidores a Qumr\u00e1n, lugar al cual llamar\u00edan Damasco.<\/p>\n<p>La comunidad esenia del Qumr\u00e1n se autoalimentaba de la agricultura, crey\u00e9ndose que eran vegetarianos, aunque en los rollos de Qumr\u00e1n no hay nada que afirme esto.<\/p>\n<p>Algunas especulaciones, relacionan a Juan Bautista y Jes\u00fas de Nazaret con los esenios, incluso Ernest Ren\u00e1n (escritor, fil\u00f3logo, fil\u00f3sofo e historiador franc\u00e9s), afirma que el esenismo triunfante, fue el germen del cristianismo.<\/p>\n<p>Otras fuentes (Evangelio de Juan), niegan esto, a causa de que Jes\u00fas asisti\u00f3 a la J\u00e1nuca (Fiesta de la Dedicaci\u00f3n), puesto que al no ser ordenada esta fiesta por la Tanaj (Biblia hebrea), los esenios la consideran fiesta ilegal.<\/p>\n<p>Tambi\u00e9n durante el siglo I exist\u00eda en Jerusal\u00e9n un barrio esenio.<\/p>\n<p>Durante el siglo XIX los escritos de All\u00e1n Kardec (escritor espiritista 1.804-1.869) y Madame Blavatsky (te\u00f3sofa 1.831-1.891) popularizaron a los esenios.<\/p>\n<p>En el a\u00f1o 1.946 son descubiertos siete de los Rollos de Qumr\u00e1n o Rollos del Mar Muerto, posteriormente, en el a\u00f1o 1.956 se encontraron el resto de manuscritos, distribuidos en 11 cuevas en la misma zona, descubrimientos que popularizaron \u00a0tambi\u00e9n a los esenios.<\/p>\n<p>Los Rollos de Qumr\u00e1n, escritos en hebreo, arameo y griego,\u00a0 fueron encontrados en unas grutas cercanas a la orilla del mar Muerto, habi\u00e9ndose encontrado un total de 972 manuscritos, datados entre los a\u00f1os 250 antes de Cristo y 66 despu\u00e9s de Cristo, antes de la destrucci\u00f3n del segundo Templo de Jerusal\u00e9n, en el a\u00f1o 70 despu\u00e9s de Cristo, por los romanos.<\/p>\n<p>Los Rollos de Qumr\u00e1n, est\u00e1n distribuidos entre el Museo de Israel en Jerusal\u00e9n, el Museo Rockefeller de Jerusal\u00e9n, la Biblioteca Nacional de Francia en Par\u00eds y en la Colecci\u00f3n Schoyen de Noruega, la cual es privada.<\/p>\n<p>Estudios divulgados principalmente por el profesor Norman Golb y la Doctora Rachel Elior, entre los a\u00f1os 1.995 y 2.009 indican que los rollos de Qumr\u00e1n (Rollos del Mar Muerto), no fueron escritos por los esenios, afirmando de fueron escritos por sacerdotes saduceos, expulsados del templo de Jerusal\u00e9n.<\/p>\n<p>La afirmaci\u00f3n de que los rollos de Qumr\u00e1n, sean de origen saduceo es negado por otras fuentes, a causa que las reglas de Qumr\u00e1n y el Documento de Damasco obligan a la comunidad de bienes, para poder ingresar en la comunidad, practicas opuestas a la comunidad saducea.<\/p>\n<p>Tambi\u00e9n durante el control saduceo del Templo (a\u00f1os 134 a 76 antes de Cristo), los autores de los rollos de Qumr\u00e1n fueron perseguidos, por lo cual no es l\u00f3gico pensar de fueran sacerdotes saduceos, sino esenios.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuentes:<\/p>\n<p><a href=\"http:\/\/es.wikipedia.org\/wiki\/Esenios\" rel=\"external nofollow\">http:\/\/es.wikipedia.org\/wiki\/Esenios<\/a><\/p>\n<p><a href=\"http:\/\/www.essenespirit.com\/spanish\/quienes.html\" rel=\"external nofollow\">http:\/\/www.essenespirit.com\/spanish\/quienes.html<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Continuamos profundizando, para intentar comprender \u201cla verdad de la religi\u00f3n\u201d, en este caso conoceremos este movimiento jud\u00edo, que se cree que se estableci\u00f3 a mediados del siglo II antes de Cristo, tras la revuelta macabea, del cual tenemos documentada su existencia hasta el siglo I, se trata de los esenios. La revuelta macabea (los macabeos, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4165","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4165"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4165\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}