{"id":4156,"date":"2016-08-19T06:45:08","date_gmt":"2016-08-19T05:45:08","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4156"},"modified":"2016-08-19T06:45:08","modified_gmt":"2016-08-19T05:45:08","slug":"geometria-sagrada","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/08\/19\/geometria-sagrada\/","title":{"rendered":"Geometr\u00eda sagrada"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/1.bp.blogspot.com\/-v6wIoLShPAU\/V7aaGsFID7I\/AAAAAAAAEJ8\/Myvjxk292qsdij-RtCIbsBctR_gNbqdVQCLcB\/s1600\/Geometria%2Bsagrada.jpg\" alt=\"\" width=\"347\" height=\"320\" \/><\/p>\n<p>Hace algunas semanas, Teodoro, me comento a ra\u00edz de un art\u00edculo que hab\u00eda publicado, que investigara sobre la geometr\u00eda sagrada metaf\u00edsica expulsionista de las sectas religiosas jud\u00edas.<\/p>\n<p>Realmente, se trata de un tema, que sinceramente no me suena de nada, pero al cotillear sobre el tema, \u201copino\u201d que puede ser interesantes escribir una serie de art\u00edculos sobre el tema, aunque, para no indigestarnos los poco conocedores de esta tem\u00e1tica, ser\u00e1 mejor que comencemos a conocer el tema desde el principio.<\/p>\n<p>En este art\u00edculo, simplemente, conoceremos en qu\u00e9 consiste la geometr\u00eda sagrada, que para m\u00ed, algo tan b\u00e1sico en el tema, ha sido todo un descubrimiento.<\/p>\n<p>Para los entendidos en el tema y los curiosos, les puedo comentar que las sectas mayoritarias, m\u00e1s activas de la \u00e9poca, fueron los Esenios, los Saduceos, los Fariseos y los Zelotes, pero esto ser\u00e1 tema de pr\u00f3ximos art\u00edculos, que ser\u00e1n publicados proximamente.<\/p>\n<p>Realmente, jam\u00e1s imagin\u00e9 que la geometr\u00eda tuviese alg\u00fan tipo de relaci\u00f3n con las religiones, pero tras el comentario de Teodoro, he comprendido que en muchas ocasiones, un simple \u00e1rbol puede tapar un bosque completo.<\/p>\n<p>Por medio de la Geometr\u00eda Sagrada, podemos comprender de forma sencilla, por la parte izquierda de nuestro cerebro, las conexiones profundas entre toda la creaci\u00f3n, permiti\u00e9ndonos a trav\u00e9s de su lenguaje simb\u00f3lico comprender mentalmente lo que ya sabemos intuitivamente.<\/p>\n<p>El Universo viene de una Inteligencia Universal (Dios, Madre Naturaleza o Gran Esp\u00edritu) y gracias a la Geometr\u00eda Sagrada, nuestra mente racional puede entender que desde un simple \u00e1tomo, hasta una galaxia est\u00e1n basados en un mismo patr\u00f3n geom\u00e9trico.<\/p>\n<p>El Arc\u00e1ngel Metatr\u00f3n, vivi\u00f3 con anterioridad en la Tierra, siendo el profeta de Enoc, siendo llevado al I reino Celestial, lugar donde fue transformado en Arc\u00e1ngel, su gemelo Sandalf\u00f3n fue el profeta de El\u00edas, consider\u00e1ndose que Metatr\u00f3n inspiro la Geometr\u00eda Sagrada, que identifica y relaciona las figuras que Dios utiliz\u00f3 para la creaci\u00f3n.<\/p>\n<p>Realmente el t\u00e9rmino Geometr\u00eda Sagrada, se refiere a las formas geom\u00e9tricas que podemos ver en lugares sagrados (mezquitas, iglesias, catedrales), las cuales van unidas a significados simb\u00f3licos y esot\u00e9ricos.<\/p>\n<p>La Geometr\u00eda Sagrada est\u00e1 asociada con la <a href=\"http:\/\/blogs.elcorreo.com\/jorbasmar\/2012\/10\/16\/masoneria\/\">\u201cMasoneria\u201d<\/a>,\u00a0 a causa de su relaci\u00f3n con la filosof\u00eda, la religi\u00f3n, las matem\u00e1ticas, la geometr\u00eda y la construcci\u00f3n de las Catedrales.<\/p>\n<p>Todo dise\u00f1o de la Geometr\u00eda Sagrada, est\u00e1 basado en cuatro componentes (conceptual, visual, relacional y pr\u00e1ctico), siendo los elementos conceptuales los elementos no visibles (punto, l\u00ednea, plano y volumen), cuando estos elementos adquieren forma, se convierten en visibles.<\/p>\n<p>Realmente la palabra forma se confunde con la palabra figura.<\/p>\n<p>Una forma tridimensional puede estar compuesta por varias figuras bidimensionales, cuando se la ve de una forma lisa.<\/p>\n<p>El asombroso n\u00famero Pi (ese n\u00famero tan inexacto que nunca se terminan sus decimales), nos expresa la relaci\u00f3n entre la longitud de la circunferencia y su di\u00e1metro.<\/p>\n<p>Todos los objetos geom\u00e9tricos regulares o semiregulares\u00a0 con simetr\u00eda pentagonal poseen la secci\u00f3n aurea y el n\u00famero \u00e1ureo.<\/p>\n<p>Tanto el n\u00famero \u00e1ureo, como la secci\u00f3n aurea, son tambi\u00e9n denominados de oro, siendo un n\u00famero irracional representado por la letra griega phi en honor al escultor griego Fidias.<\/p>\n<p>En la Geometr\u00eda Sagrada hay siete formas geom\u00e9tricas principales, los cinco s\u00f3lidos plat\u00f3nicos, el c\u00edrculo y la espiral.<\/p>\n<p>Para Plat\u00f3n existen cinco s\u00f3lidos tridimensionales de aristas, caras y lados iguales llamados los s\u00f3lidos plat\u00f3nicos (tetraedro, cubo, octaedro, icosaedro y dodecaedro) donde Plat\u00f3n afirma en su di\u00e1logo el Timeo, que Dios utilizo el dodecaedro para dibujar el plano del Universo.<\/p>\n<p>Se relacionan los s\u00f3lidos plat\u00f3nicos, con los elementos de la siguiente forma, el tetraedro con el fuego, el cubo con la Tierra, el octaedro con el aire, el icosaedro con el agua y el dodecaedro con el \u00e9ter o Akasha.<\/p>\n<p>Madame Blavatsky, escritora de <a href=\"http:\/\/www.alejandriadigital.com\/2016\/01\/10\/la-doctrina-secreta-de-madame-blavatsky-en-pdf-6-tomos-2783-paginas-en-un-solo-archivo-en-pdf\/\" rel=\"external nofollow\">\u201cLa Doctrina Secreta\u201d<\/a>, nos cuenta que existen cinco llaves para interpretar la vida,\u00a0 la fisiol\u00f3gica, la psicol\u00f3gica, la astrol\u00f3gica, la metaf\u00edsica y la geometr\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuentes:<\/p>\n<p><a href=\"https:\/\/www.google.es\/?ion=1&#038;espv=2#q=geometria%20sagrada\" rel=\"external nofollow\">https:\/\/www.google.es\/?ion=1&#038;espv=2#q=geometria%20sagrada<\/a><\/p>\n<p><a href=\"http:\/\/www.orgonitesatlantis.com\/la-geometria-sagrada\/\" rel=\"external nofollow\">http:\/\/www.orgonitesatlantis.com\/la-geometria-sagrada\/<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hace algunas semanas, Teodoro, me comento a ra\u00edz de un art\u00edculo que hab\u00eda publicado, que investigara sobre la geometr\u00eda sagrada metaf\u00edsica expulsionista de las sectas religiosas jud\u00edas. Realmente, se trata de un tema, que sinceramente no me suena de nada, pero al cotillear sobre el tema, \u201copino\u201d que puede ser interesantes escribir una serie de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4156","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4156"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4156\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}