{"id":4155,"date":"2016-08-18T05:55:41","date_gmt":"2016-08-18T04:55:41","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4155"},"modified":"2016-08-18T05:55:41","modified_gmt":"2016-08-18T04:55:41","slug":"copa-de-higos-y-cerezas-con-natillas","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/08\/18\/copa-de-higos-y-cerezas-con-natillas\/","title":{"rendered":"Copa de higos y cerezas con natillas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/4.bp.blogspot.com\/-OC4FtWejPT4\/V7U8y-RVZbI\/AAAAAAAAEJg\/Pe-t9WZVp_c8ItiZK-W-u1qHMzyk22lIQCLcB\/s320\/Copa%2Bde%2Bhigos%2By%2Bcerezas%2Bcon%2Bnatillas.JPG\" alt=\"\" width=\"320\" height=\"239\" \/><\/p>\n<p>Este postre permite realizarle todas las variaciones que se os ocurran, adem\u00e1s de ser muy f\u00e1cil de realizar.<\/p>\n<p>Se trata de combinar unas natillas, un yogurt, crema pastelera, lo que teng\u00e1is perdido en la nevera y combinarlo con cualquier fruta que teng\u00e1is olvidada en vuestra nevera.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>1 tarrina de natillas de chocolate<\/strong><\/p>\n<p><strong>3 higos<\/strong><\/p>\n<p><strong>Cerezas<\/strong><\/p>\n<p><strong>2 cucharadas de miel<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Repartimos en el fondo de dos copas la tarrina de natillas.<\/p>\n<p>Troceamos a trozos aptos para la cuchara de postre los higos, colocando la mitad de sus trocitos en cada copa.<\/p>\n<p>Terminamos de llenar la copa con mitades de cerezas, previamente deshuesadas.<\/p>\n<p>Culminamos cada una de nuestras copas, con una generosa cucharada sopera de miel.<\/p>\n<p>Guardamos en el frigor\u00edfico hasta el momento de servir.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Este postre permite realizarle todas las variaciones que se os ocurran, adem\u00e1s de ser muy f\u00e1cil de realizar. Se trata de combinar unas natillas, un yogurt, crema pastelera, lo que teng\u00e1is perdido en la nevera y combinarlo con cualquier fruta que teng\u00e1is olvidada en vuestra nevera. &nbsp; Ingredientes (2 personas): \u00a0 1 tarrina de natillas [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4155","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4155"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4155\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}