{"id":4143,"date":"2016-08-06T06:41:15","date_gmt":"2016-08-06T05:41:15","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4143"},"modified":"2016-08-06T06:41:15","modified_gmt":"2016-08-06T05:41:15","slug":"fajitas-de-tortilla-cuadrada-de-brocoli","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/08\/06\/fajitas-de-tortilla-cuadrada-de-brocoli\/","title":{"rendered":"Fajitas de tortilla cuadrada de brocoli"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/2.bp.blogspot.com\/-pSUbUVVDJA8\/V6V1UzexqJI\/AAAAAAAAEFw\/08N0OvXORicSH5S79H20e-qazZOh338dgCLcB\/s320\/Fajitas%2Bde%2Btortilla%2Bcuadrada%2Bde%2Bbrocoli.jpg\" alt=\"\" width=\"320\" height=\"239\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Como sab\u00e9is los habituales de este espacio, siempre ando utilizando sobras, en este caso ten\u00eda sobrante de otra receta, unos trozos de br\u00f3coli cocido, que no sab\u00eda qu\u00e9 hacer con \u00e9l, adem\u00e1s ten\u00eda exceso de huevos de nuestras gallinas y una caja de fajitas sin empezar\u2026 pues con esto y una simple ensalada, ya tenemos una estupenda cena a la fresca, que se puede preparar con anterioridad y antes de servir darle un toke de horno.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>4 fajitas<\/strong><\/p>\n<p><strong>6 huevos<\/strong><\/p>\n<p><strong>Sobras de br\u00f3coli cocido<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Curry<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Comenzamos por realizar una tortilla cuadrada, puesto que de esta forma, nos quedara perfecta para cortar tiras del mismo tama\u00f1o, para envolver con las fajitas (si no ten\u00e9is sart\u00e9n cuadrada, pues redonda tambi\u00e9n sirve).<\/p>\n<p>Al ser los huevos caseros, cuesta bastante batirlos, por lo cual introduje los seis huevos en el vaso de la batidora, junto la sal y el curry.<\/p>\n<p>Trituramos y posteriormente a\u00f1adimos el br\u00f3coli troceado.<\/p>\n<p>Colocamos en nuestra sart\u00e9n, un abundante chorro de aceite de oliva y cuando est\u00e9 bien caliente, a\u00f1adimos el contenido del vaso de la batidora.<\/p>\n<p>Realizamos la tortilla d\u00e1ndole las vueltas que consideremos necesarias y colocamos en un plato para que se enfr\u00ede un poco y poder trabajar c\u00f3modos con ella.<\/p>\n<p>Una vez fr\u00eda o templada, cortamos la tortilla a bastoncitos del tama\u00f1o que consideremos adecuado para las fajitas y envolvemos con una fajita cada bastoncito de tortilla.<\/p>\n<p>Colocamos en la bandeja de horno previamente aceitada y rociamos un poquito m\u00e1s de aceite sobre la fajita.<\/p>\n<p>Horneamos a 160\u00ba unos 10-15 minutos, a partir de horno fr\u00edo y gratinamos 5-10 minutos, antes de servir.<\/p>\n<p>Que aproveche.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Como sab\u00e9is los habituales de este espacio, siempre ando utilizando sobras, en este caso ten\u00eda sobrante de otra receta, unos trozos de br\u00f3coli cocido, que no sab\u00eda qu\u00e9 hacer con \u00e9l, adem\u00e1s ten\u00eda exceso de huevos de nuestras gallinas y una caja de fajitas sin empezar\u2026 pues con esto y una simple ensalada, ya [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4143","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4143"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4143\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}