{"id":4120,"date":"2016-07-15T06:46:04","date_gmt":"2016-07-15T05:46:04","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4120"},"modified":"2016-07-15T06:46:04","modified_gmt":"2016-07-15T05:46:04","slug":"estrellitas-de-almendra-y-datiles","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/07\/15\/estrellitas-de-almendra-y-datiles\/","title":{"rendered":"Estrellitas de almendra y datiles"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"\/\/i.imgur.com\/yKecrUH.jpg\" alt=\"\" width=\"569\" height=\"320\" \/><\/p>\n<p>Aunque se me chamuscaron un poco las esquinitas, quedaron deliciosas estas estrellitas y adem\u00e1s son muy f\u00e1ciles de realizar.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (10 estrellitas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>125 g de harina de almendras<\/strong><\/p>\n<p><strong>10 d\u00e1tiles secos<\/strong><\/p>\n<p><strong>75 g de mantequilla<\/strong><\/p>\n<p><strong>75 g de az\u00facar<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>En primer lugar, deshuesamos los d\u00e1tiles y reservamos.<\/p>\n<p>En un recipiente introducimos la harina de almendra (podemos obtenerla moliendo almendras peladas), la mantequilla, el az\u00facar y un poco de sal.<\/p>\n<p>Mezclamos bien hasta integrar todos los ingredientes.<\/p>\n<p>Necesitaremos tambi\u00e9n moldes de silicona con forma de estrella (aunque con la textura de la masa no es necesario molde, pero si queremos darle forma de estrella\u2026), llenamos los moldes hasta la mitad de masa.<\/p>\n<p>Introducimos un d\u00e1til previamente deshuesado en cada molde y terminamos de rellenar el molde con el resto de la masa, escondiendo el d\u00e1til en el interior de nuestra estrella.<\/p>\n<p>Horneamos a 220\u00ba a partir de horno fr\u00edo unos 25 minutos (yo lo horne\u00e9 30 minutos).<\/p>\n<p>Dejar enfriar, desmoldar y comer.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Aunque se me chamuscaron un poco las esquinitas, quedaron deliciosas estas estrellitas y adem\u00e1s son muy f\u00e1ciles de realizar. &nbsp; Ingredientes (10 estrellitas): \u00a0 125 g de harina de almendras 10 d\u00e1tiles secos 75 g de mantequilla 75 g de az\u00facar Sal \u00a0 Preparaci\u00f3n: \u00a0 En primer lugar, deshuesamos los d\u00e1tiles y reservamos. En un [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4120","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4120"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4120\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}