{"id":4118,"date":"2016-07-13T07:00:06","date_gmt":"2016-07-13T06:00:06","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4118"},"modified":"2016-07-13T07:00:06","modified_gmt":"2016-07-13T06:00:06","slug":"rollitos-mexicanos-con-tortilla-y-tomate","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/07\/13\/rollitos-mexicanos-con-tortilla-y-tomate\/","title":{"rendered":"Rollitos mexicanos con tortilla y tomate"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/1.bp.blogspot.com\/-aFDqyBIvEcA\/V4XXQuaMgaI\/AAAAAAAAD88\/r9ld27m0jqEA-W3I8yAfKhklBXob81wJQCLcB\/s320\/16s9yo.gif\" alt=\"\" width=\"320\" height=\"284\" \/><\/p>\n<p>En esta ocasi\u00f3n os presento una receta m\u00e1s entre mis habituales recetas de sobras.<\/p>\n<p>Realmente, con un poco de imaginaci\u00f3n y cuatro ingredientes sueltos, que tengamos en casa, se pueden realizar estupendas y vistosas recetas, casi sin trabajar, ni manchar en la cocina.<\/p>\n<p>En este caso, el otro d\u00eda nos sobr\u00f3 media <a href=\"http:\/\/jorbasmar.blogspot.com.es\/2016\/07\/tortilla-cuadrada-de-patatas-con.html\" rel=\"external nofollow\">\u201cTortilla cuadrada de patatas, cebolla, esp\u00e1rragos y pimientos\u201d<\/a>, con la cual ha salido esta estupenda cena.<\/p>\n<p>&nbsp;<\/p>\n<p>Receta para realizar la tortilla cuadrada:<\/p>\n<p><a href=\"http:\/\/jorbasmar.blogspot.com.es\/2016\/07\/tortilla-cuadrada-de-patatas-con.html\" rel=\"external nofollow\">http:\/\/jorbasmar.blogspot.com.es\/2016\/07\/tortilla-cuadrada-de-patatas-con.html<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (4 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Sobras de tortilla<\/strong><\/p>\n<p><strong>2 tortitas mexicanas<\/strong><\/p>\n<p><strong>1 tomate maduro<\/strong><\/p>\n<p><strong>4 l\u00e1minas de pepinillo en vinagre<\/strong><\/p>\n<p><strong>Pimientos rojos de lata (para decorar)<\/strong><\/p>\n<p><strong>Aceitunas negras (para decorar)<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Lavamos y cortamos finito (en l\u00e1minas) el tomate.<\/p>\n<p>Extendemos las rodajas de tomate, reparti\u00e9ndolo entre ambas tortitas mexicanas.<\/p>\n<p>Sobre el tomate colocamos dos lonchas de pepinillo en vinagre.<\/p>\n<p>Repartimos las sobras de tortilla sobre el tomate y el pepinillo.<\/p>\n<p>Envolvemos con las tortitas mexicanas.<\/p>\n<p>Decoramos las tortitas mexicanas con aceitunas negras sin hueso y tiras de pimiento de lata.<\/p>\n<p>Horneamos con calor arriba y abajo 10-15 minutos a 160\u00ba, a partir de horno fr\u00edo.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En esta ocasi\u00f3n os presento una receta m\u00e1s entre mis habituales recetas de sobras. Realmente, con un poco de imaginaci\u00f3n y cuatro ingredientes sueltos, que tengamos en casa, se pueden realizar estupendas y vistosas recetas, casi sin trabajar, ni manchar en la cocina. En este caso, el otro d\u00eda nos sobr\u00f3 media \u201cTortilla cuadrada de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4118","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4118"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4118\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}