{"id":4117,"date":"2016-07-12T07:17:54","date_gmt":"2016-07-12T06:17:54","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4117"},"modified":"2016-07-12T07:17:54","modified_gmt":"2016-07-12T06:17:54","slug":"hamburguesa-de-tortilla-de-esparragos","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/07\/12\/hamburguesa-de-tortilla-de-esparragos\/","title":{"rendered":"Hamburguesa de tortilla de esp\u00e1rragos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"\/\/i.imgur.com\/zNgeguX.jpg\" alt=\"\" width=\"569\" height=\"320\" \/><\/p>\n<p>Hoy os presento una receta muy tonta, pero me ha apetecido gastar unos panes de hamburguesa que ten\u00eda en casa, unos esp\u00e1rragos de maceta y dos huevos de gallina, que se me comienzan a acumular en casa.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>2 huevos<\/strong><\/p>\n<p><strong>1 pu\u00f1adito de esp\u00e1rragos trigueros<\/strong><\/p>\n<p><strong>1 tomate<\/strong><\/p>\n<p><strong>\u00bd cebolla<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>La realizaci\u00f3n de esta hamburguesa es s\u00faper dif\u00edcil, hace falta una sart\u00e9n muy peque\u00f1a (pero se puede hacer m\u00e1s grande y cortarla a trozos o simplemente doblarla).<\/p>\n<p>Troceamos la parte tierna de los esp\u00e1rragos, desechando la parte dura.<\/p>\n<p>Batimos un huevo con sal y la mitad de la parte tierna de los esp\u00e1rragos.<\/p>\n<p>Colocamos un poco de aceite en la sart\u00e9n, vertemos el huevo con los esp\u00e1rragos y realizamos una tortilla.<\/p>\n<p>Realizamos otra tortilla con el huevo y los esp\u00e1rragos restantes.<\/p>\n<p>Solo nos resta, cortar en rodajas la cebolla y el tomate.<\/p>\n<p>Abrimos en dos los panes de hamburguesa y aceitamos sus dos partes interiores con un generoso chorro de aceite de oliva.<\/p>\n<p>Sobre la parte inferior de cada panecillo, repartimos las rodajas de tomate.<\/p>\n<p>Sobre el tomate colocamos las tortillas.<\/p>\n<p>Cubrimos las tortillas con las rodajas de cebolla.<\/p>\n<p>Tapamos con la parte sobrante del panecillo.<\/p>\n<p>Antes de servir, se puede calentar al horno a 150\u00ba unos 15 minutos a partir de horno fr\u00edo, para obtener un delicioso pan calentito y crujiente.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy os presento una receta muy tonta, pero me ha apetecido gastar unos panes de hamburguesa que ten\u00eda en casa, unos esp\u00e1rragos de maceta y dos huevos de gallina, que se me comienzan a acumular en casa. &nbsp; Ingredientes (2 personas): \u00a0 2 huevos 1 pu\u00f1adito de esp\u00e1rragos trigueros 1 tomate \u00bd cebolla Aceite de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4117","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4117"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4117\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}