{"id":4092,"date":"2016-06-17T07:14:03","date_gmt":"2016-06-17T06:14:03","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4092"},"modified":"2016-06-17T07:14:03","modified_gmt":"2016-06-17T06:14:03","slug":"pastel-de-atun-y-jamon","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/06\/17\/pastel-de-atun-y-jamon\/","title":{"rendered":"Pastel de at\u00fan y jam\u00f3n"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"\/\/i.imgur.com\/x2nHqN6.jpg\" alt=\"\" width=\"569\" height=\"320\" \/><\/p>\n<p>Hoy os traigo una cena muy simple, pero rica y con muy poco trabajo.<\/p>\n<p>En esta ocasi\u00f3n, la receta la preparo mi mujer, Silvia.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>6 rebanadas de pan de molde<\/strong><\/p>\n<p><strong>1 huevo cocido<\/strong><\/p>\n<p><strong>2 lonchas de jam\u00f3n salado<\/strong><\/p>\n<p><strong>1 lata de at\u00fan en aceite<\/strong><\/p>\n<p><strong>4 aceitunas sin hueso para decorar<\/strong><\/p>\n<p><strong>2 tomates maduros<\/strong><\/p>\n<p><strong>Aceite de oliva<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>En primer lugar lavamos y troceamos los tomates, les a\u00f1adimos aceite y sal al gusto y tritur\u00e1ndolos con la batidora.<\/p>\n<p>Untamos una de las caras de una rebanada de pan de molde con la salsita de tomate que hemos triturado y colocamos sobre ella una loncha de jam\u00f3n salado.<\/p>\n<p>Cubrimos con otra rebanada de pan de molde, la cual cubriremos con at\u00fan en aceite.<\/p>\n<p>Colocamos sobre\u00a0 el at\u00fan otra rebanada de pan de molde que tambi\u00e9n untaremos con la salsa de tomate.<\/p>\n<p>Cortamos todo el montadito que tenemos preparado en cuatro trozos para facilitar comerlo.<\/p>\n<p>Decoramos con medio huevo duro (el huevo cocido de la foto tiene forma de pez, se obtiene esta forma, pelando el huevo reci\u00e9n cocido e introduci\u00e9ndolo en un molde).<\/p>\n<p>Decoramos tambi\u00e9n con dos aceitunas sin hueso cortadas por la mitad.<\/p>\n<p>Repetimos la operaci\u00f3n con las otras tres rebanadas restantes.<\/p>\n<p>Guardar en el frigor\u00edfico hasta el momento de servir.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy os traigo una cena muy simple, pero rica y con muy poco trabajo. En esta ocasi\u00f3n, la receta la preparo mi mujer, Silvia. &nbsp; Ingredientes (2 personas): \u00a0 6 rebanadas de pan de molde 1 huevo cocido 2 lonchas de jam\u00f3n salado 1 lata de at\u00fan en aceite 4 aceitunas sin hueso para decorar [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4092","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4092"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4092\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}