{"id":4080,"date":"2016-06-04T06:12:11","date_gmt":"2016-06-04T05:12:11","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4080"},"modified":"2016-06-04T06:12:11","modified_gmt":"2016-06-04T05:12:11","slug":"melon-grand-marnier","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/06\/04\/melon-grand-marnier\/","title":{"rendered":"Melon Grand Marnier"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"\/\/i.imgur.com\/rVR0lEt.jpg\" alt=\"\" width=\"427\" height=\"320\" \/><\/p>\n<p>Hoy os traigo un cl\u00e1sico de mi cocina, que generalmente lo aderezo con Moriles (vino blanco fino y seco andaluz), pero en esta ocasi\u00f3n he querido probar con un licor, para que la receta no sea igual que siempre.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>1 mel\u00f3n de Galia gordito o 2 peque\u00f1os (para parejas queda mejor uno grande con dos pajitas)<\/strong><\/p>\n<p><strong>75 g de az\u00facar<\/strong><\/p>\n<p><strong>1 chupito de Grand Marnier<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><br \/>\nCortamos una rodaja finita de la piel de uno de los extremos del mel\u00f3n, para poder acceder a su interior con la ayuda de un saca bolas y la reservamos para posteriormente tapar el mel\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Colocamos la carne del mel\u00f3n en el vaso de la batidora y desechamos sus semillas (si ten\u00e9is paciencia pod\u00e9is colocarlas al sol, esperar que se sequen y comerlas como si fueran pipas de girasol, pero yo opte por d\u00e1rselas a las gallinas a cambio de sus huevos).<\/p>\n<p>&nbsp;<\/p>\n<p>A\u00f1adimos una generosa cucharada de az\u00facar a la carne del mel\u00f3n (recordad que fr\u00eda esta menos dulce) y trituramos.<\/p>\n<p>&nbsp;<\/p>\n<p>Volcamos la crema obtenida en el interior del mel\u00f3n y terminamos de rellenarlo con el Grand Marnier.<\/p>\n<p>&nbsp;<\/p>\n<p>En la rodaja de piel de mel\u00f3n, que hemos reservado con anterioridad, practicamos un agujero, con la ayuda de un saca corazones de manzanas, para posteriormente introducir las pajitas.<\/p>\n<p>&nbsp;<\/p>\n<p>Se guarda en la nevera y se sirve lo m\u00e1s\u00a0frio posible.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy os traigo un cl\u00e1sico de mi cocina, que generalmente lo aderezo con Moriles (vino blanco fino y seco andaluz), pero en esta ocasi\u00f3n he querido probar con un licor, para que la receta no sea igual que siempre. &nbsp; Ingredientes (2 personas): \u00a0 1 mel\u00f3n de Galia gordito o 2 peque\u00f1os (para parejas queda [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4080","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4080"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4080\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}