{"id":4077,"date":"2016-06-01T05:47:28","date_gmt":"2016-06-01T04:47:28","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=4077"},"modified":"2016-06-01T05:47:28","modified_gmt":"2016-06-01T04:47:28","slug":"pina-con-yogurt-de-coco","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/06\/01\/pina-con-yogurt-de-coco\/","title":{"rendered":"Pi\u00f1a con yogurt de coco"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"\/\/i.imgur.com\/jyOMXWO.jpg\" alt=\"\" width=\"427\" height=\"320\" \/><\/p>\n<p>Seguimos con la colecci\u00f3n de postres para vagos, con buena presentaci\u00f3n, poco trabajo y estupendo sabor.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (2 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>4 rodajas de pi\u00f1a natural<\/strong><\/p>\n<p><strong>2 cucharadas soperas de leche condensada<\/strong><\/p>\n<p><strong>1 yogurt de coco<\/strong><\/p>\n<p><strong>4 fresas<\/strong><\/p>\n<p><strong>Calabaza verde confitada<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Desechamos la piel y la parte central de las rodajas de pi\u00f1a y cortamos la pi\u00f1a en trocitos peque\u00f1os aptos para una cuchara de postre.<\/p>\n<p>Repartimos los trozos de pi\u00f1a en dos copas y colocamos sobre la pi\u00f1a la leche condensada.<\/p>\n<p>A continuaci\u00f3n repartimos el yogurt en ambas copas.<\/p>\n<p>Lavamos y troceamos las fresas, decorando ambas copas con ellas y dos trocitos de calabaza verde confitada.<\/p>\n<p>Conservar en el frigor\u00edfico hasta el momento de servir.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Seguimos con la colecci\u00f3n de postres para vagos, con buena presentaci\u00f3n, poco trabajo y estupendo sabor. &nbsp; Ingredientes (2 personas): \u00a0 4 rodajas de pi\u00f1a natural 2 cucharadas soperas de leche condensada 1 yogurt de coco 4 fresas Calabaza verde confitada Preparaci\u00f3n: \u00a0 Desechamos la piel y la parte central de las rodajas de pi\u00f1a [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4077","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=4077"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/4077\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=4077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=4077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=4077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}