{"id":3956,"date":"2016-02-15T07:00:39","date_gmt":"2016-02-15T06:00:39","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/jorbasmar\/?p=3956"},"modified":"2016-02-15T07:00:39","modified_gmt":"2016-02-15T06:00:39","slug":"tortilla-de-patatas-y-pimientos-del-piquillo","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/jorbasmar\/2016\/02\/15\/tortilla-de-patatas-y-pimientos-del-piquillo\/","title":{"rendered":"Tortilla de patatas y pimientos del piquillo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"\/\/i.imgur.com\/jWZeY4d.jpg\" alt=\"\" width=\"427\" height=\"320\" \/><\/p>\n<p>En esta ocasi\u00f3n os traigo la conocida tortilla de patatas, con la variaci\u00f3n de colocarle pimientos del piquillo en lugar de la controvertida cebolla, que de esta forma le daremos un toque de color.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredientes (4-6 personas):<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>6 huevos<\/strong><\/p>\n<p><strong>8 pimientos del piquillo de lata<\/strong><\/p>\n<p><strong>2 patatas peque\u00f1as<\/strong><\/p>\n<p><strong>Sal<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>En primer lugar pelamos, troceamos y fre\u00edmos las patatas a baja temperatura, para que nos queden tiernas, pero no tostadas.<\/p>\n<p>Mientras a fuego muy lento tambi\u00e9n fre\u00edmos los pimientos del piquillo (aunque no es necesario), personalmente me gusta m\u00e1s fre\u00edrlos para que queden muy blanditos.<\/p>\n<p>Escurrimos las patatas y los pimientos del exceso de aceite y dejamos enfriar un poco.<\/p>\n<p>Mientras cascamos los huevos, los salamos y batimos.<\/p>\n<p>A\u00f1adimos las patatas y los pimientos a los huevos batidos, dejamos juntos todos los ingredientes unos minutos para que las patatas y los pimientos se impregnen bien del huevo.<\/p>\n<p>Colocamos una sart\u00e9n al fuego con aceite y cuando se caliente volcamos los huevos junto con las verduras y confeccionamos la tortilla, d\u00e1ndole todas las vueltas que consideremos necesarias, hasta que tenga el nivel de tostado que deseemos.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En esta ocasi\u00f3n os traigo la conocida tortilla de patatas, con la variaci\u00f3n de colocarle pimientos del piquillo en lugar de la controvertida cebolla, que de esta forma le daremos un toque de color. &nbsp; Ingredientes (4-6 personas): \u00a0 6 huevos 8 pimientos del piquillo de lata 2 patatas peque\u00f1as Sal \u00a0 Preparaci\u00f3n: \u00a0 En [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":40311,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3956","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/3956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/users\/40311"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/comments?post=3956"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/posts\/3956\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/media?parent=3956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/categories?post=3956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/jorbasmar\/wp-json\/wp\/v2\/tags?post=3956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}