{"id":4153,"date":"2012-06-16T10:51:53","date_gmt":"2012-06-16T09:51:53","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=4153"},"modified":"2012-06-16T10:51:53","modified_gmt":"2012-06-16T09:51:53","slug":"en-pie-crea-un-observatorio-de-sanidad-para-conocer-las-consecuencias-de-los-recortes","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2012\/06\/16\/en-pie-crea-un-observatorio-de-sanidad-para-conocer-las-consecuencias-de-los-recortes\/","title":{"rendered":"En Pie crea un Observatorio de Sanidad para conocer las consecuencias de los recortes"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5><span style=\"color: #0000ff;\">Miranda<\/span><\/h5>\n<p><a href=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/06\/mir17-06-12blog.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-4154\" title=\"mir17-06-12blog\" src=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/06\/mir17-06-12blog.jpg\" alt=\"\" width=\"599\" height=\"156\" srcset=\"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/06\/mir17-06-12blog.jpg 1031w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/06\/mir17-06-12blog-300x78.jpg 300w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/06\/mir17-06-12blog-768x200.jpg 768w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/06\/mir17-06-12blog-1024x267.jpg 1024w\" sizes=\"auto, (max-width: 599px) 100vw, 599px\" \/><\/a><\/p>\n<p>No est\u00e1n dispuestos a asumir la perdida en la calidad del servicio y a que se impongan el repago de servicios por los que los ciudadanos ya han contribuido, por eso la plataforma ciudadana En Pie ha decidido poner en marcha un Observatorio de Sanidad.<a href=\"http:\/\/www.elcorreo.com\/alava\/v\/20120616\/miranda\/crea-observatorio-sanidad-para-20120616.html\" rel=\"external nofollow\"> (+)<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Miranda No est\u00e1n dispuestos a asumir la perdida en la calidad del servicio y a que se impongan el repago de servicios por los que los ciudadanos ya han contribuido, por eso la plataforma ciudadana En Pie ha decidido poner en marcha un Observatorio de Sanidad. (+)<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[5932,6315],"class_list":["post-4153","post","type-post","status-publish","format-standard","hentry","category-tiras-de-miranda","tag-recortes","tag-sanidad"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/4153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=4153"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/4153\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=4153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=4153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=4153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}