{"id":4035,"date":"2012-05-26T09:55:30","date_gmt":"2012-05-26T08:55:30","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=4035"},"modified":"2012-05-26T09:55:30","modified_gmt":"2012-05-26T08:55:30","slug":"los-actos-centrales-de-la-fiesta-restringen-el-trafico-para-dar-mas-espacio-a-los-blusas","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2012\/05\/26\/los-actos-centrales-de-la-fiesta-restringen-el-trafico-para-dar-mas-espacio-a-los-blusas\/","title":{"rendered":"Los actos centrales de la fiesta restringen el tr\u00e1fico para dar m\u00e1s espacio a los blusas"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5><span style=\"color: #0000ff;\">Miranda<\/span><\/h5>\n<p><a href=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir26-05-12blog.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-4036\" title=\"mir26-05-12blog\" src=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir26-05-12blog.jpg\" alt=\"\" width=\"599\" height=\"156\" srcset=\"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir26-05-12blog.jpg 1031w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir26-05-12blog-300x78.jpg 300w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir26-05-12blog-768x200.jpg 768w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir26-05-12blog-1024x267.jpg 1024w\" sizes=\"auto, (max-width: 599px) 100vw, 599px\" \/><\/a><\/p>\n<p>San Juan no es una fiesta para moverse en coche. As\u00ed que para facilitar el desarrollo de determinados actos desde el Ayuntamiento se ha fijado un plan de actuaciones para limitar el estacionamiento y la circulaci\u00f3n de coches. <a href=\"http:\/\/www.elcorreo.com\/alava\/v\/20120526\/miranda\/actos-centrales-fiesta-restringen-20120526.html\" rel=\"external nofollow\">(+)<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Miranda San Juan no es una fiesta para moverse en coche. As\u00ed que para facilitar el desarrollo de determinados actos desde el Ayuntamiento se ha fijado un plan de actuaciones para limitar el estacionamiento y la circulaci\u00f3n de coches. (+)<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[3138,4315,6885],"class_list":["post-4035","post","type-post","status-publish","format-standard","hentry","category-tiras-de-miranda","tag-fiesta","tag-logistica","tag-trafico"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/4035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=4035"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/4035\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=4035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=4035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=4035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}