{"id":3974,"date":"2012-05-17T09:07:52","date_gmt":"2012-05-17T08:07:52","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=3974"},"modified":"2012-05-17T09:07:52","modified_gmt":"2012-05-17T08:07:52","slug":"miranda-contiene-su-contaminacion","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2012\/05\/17\/miranda-contiene-su-contaminacion\/","title":{"rendered":"Miranda contiene su contaminaci\u00f3n"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5><span style=\"color: #0000ff;\">Miranda<\/span><\/h5>\n<p><a href=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir17-05-12blog2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3977\" title=\"mir17-05-12blog\" src=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir17-05-12blog2.jpg\" alt=\"\" width=\"601\" height=\"156\" srcset=\"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir17-05-12blog2.jpg 1031w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir17-05-12blog2-300x78.jpg 300w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir17-05-12blog2-768x200.jpg 768w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir17-05-12blog2-1024x266.jpg 1024w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" \/><\/a><\/p>\n<p>La atm\u00f3sfera de la ciudad se transforma; es cada vez m\u00e1s inocua. Es lo que indican los valores recogidos en el \u00faltimo informe elaborado por el departamento de Medio Ambiente de la Junta de Castilla y Le\u00f3n. Un documento que evidencia, por primera vez desde hace m\u00e1s de una d\u00e9cada, que Miranda se encuentra muy alejada de la cota de los 35 d\u00edas al a\u00f1o que la Directiva Europea sobre la Calidad del Aire Ambiente considera insuperable en lo que se refiere a las emisiones de part\u00edculas en suspensi\u00f3n.\u00a0 <a href=\"http:\/\/www.elcorreo.com\/alava\/v\/20120517\/miranda\/miranda-contiene-contaminacion-20120517.html\" rel=\"external nofollow\">(+)<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Miranda La atm\u00f3sfera de la ciudad se transforma; es cada vez m\u00e1s inocua. Es lo que indican los valores recogidos en el \u00faltimo informe elaborado por el departamento de Medio Ambiente de la Junta de Castilla y Le\u00f3n. Un documento que evidencia, por primera vez desde hace m\u00e1s de una d\u00e9cada, que Miranda se [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[5190,6653],"class_list":["post-3974","post","type-post","status-publish","format-standard","hentry","category-tiras-de-miranda","tag-particulas","tag-suspension"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/3974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=3974"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/3974\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=3974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=3974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=3974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}