{"id":3889,"date":"2012-05-04T08:01:01","date_gmt":"2012-05-04T07:01:01","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=3889"},"modified":"2012-05-04T08:01:01","modified_gmt":"2012-05-04T07:01:01","slug":"madrid-acepta-el-plan-de-ajuste-y-habilita-el-pago-a-proveedores","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2012\/05\/04\/madrid-acepta-el-plan-de-ajuste-y-habilita-el-pago-a-proveedores\/","title":{"rendered":"Madrid acepta el plan de ajuste y habilita el pago a proveedores"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5><span style=\"color: #0000ff;\">Miranda<\/span><\/h5>\n<p><a href=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir04-05-12blog.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3890\" title=\"mir04-05-12blog\" src=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir04-05-12blog.jpg\" alt=\"\" width=\"599\" height=\"156\" srcset=\"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir04-05-12blog.jpg 1031w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir04-05-12blog-300x78.jpg 300w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir04-05-12blog-768x200.jpg 768w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/05\/mir04-05-12blog-1024x267.jpg 1024w\" sizes=\"auto, (max-width: 599px) 100vw, 599px\" \/><\/a><\/p>\n<p>El Ministerio de Hacienda y Administraciones P\u00fablicas da un respiro al Ayuntamiento de Miranda.\u00a0 Su Secretar\u00eda ha informado de manera favorable al plan de ajuste para los pr\u00f3ximos diez a\u00f1os, lo que implica que, en cuesti\u00f3n de semanas, se canalizar\u00e1 a trav\u00e9s de un consorcio de bancos y cajas de ahorro, los cerca de 6,5 millones de euros que la ciudad declar\u00f3 como deuda con m\u00e1s de 300 proveedores&#8230; <a href=\"http:\/\/www.elcorreo.com\/alava\/v\/20120504\/miranda\/madrid-acepta-plan-ajuste-20120504.html\" rel=\"external nofollow\">(+)<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Miranda El Ministerio de Hacienda y Administraciones P\u00fablicas da un respiro al Ayuntamiento de Miranda.\u00a0 Su Secretar\u00eda ha informado de manera favorable al plan de ajuste para los pr\u00f3ximos diez a\u00f1os, lo que implica que, en cuesti\u00f3n de semanas, se canalizar\u00e1 a trav\u00e9s de un consorcio de bancos y cajas de ahorro, los cerca [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[5639,5746],"class_list":["post-3889","post","type-post","status-publish","format-standard","hentry","category-tiras-de-miranda","tag-prestamo","tag-proveedores"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/3889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=3889"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/3889\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=3889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=3889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=3889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}