{"id":3681,"date":"2012-03-26T10:44:55","date_gmt":"2012-03-26T09:44:55","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=3681"},"modified":"2012-03-26T10:44:55","modified_gmt":"2012-03-26T09:44:55","slug":"el-alto-coste-de-la-calefaccion-moviliza-a-los-vecinos-de-las-nuevas-casas-de-zabalgana","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2012\/03\/26\/el-alto-coste-de-la-calefaccion-moviliza-a-los-vecinos-de-las-nuevas-casas-de-zabalgana\/","title":{"rendered":"El alto coste de la calefacci\u00f3n moviliza a los vecinos de las nuevas casas de Zabalgana"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5><span style=\"color: #008000;\">Araba\/\u00c1lava<\/span><\/h5>\n<p><a href=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/03\/26-03-12blog.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3682\" title=\"26-03-12blog\" src=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/03\/26-03-12blog.jpg\" alt=\"\" width=\"604\" height=\"155\" srcset=\"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/03\/26-03-12blog.jpg 1031w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/03\/26-03-12blog-300x77.jpg 300w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/03\/26-03-12blog-768x197.jpg 768w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/03\/26-03-12blog-1024x263.jpg 1024w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/a><\/p>\n<p>La cuenta corriente de almudena Beltr\u00e1n recibe cada mes una certera pu\u00f1alada que le desangra, de un solo golpe, casi doscientos euros&#8230;\u00a0 (+ info en el papel)<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Araba\/\u00c1lava La cuenta corriente de almudena Beltr\u00e1n recibe cada mes una certera pu\u00f1alada que le desangra, de un solo golpe, casi doscientos euros&#8230;\u00a0 (+ info en el papel)<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[3048,3267,3370,3383],"class_list":["post-3681","post","type-post","status-publish","format-standard","hentry","category-tiras-de-alava","tag-facturon","tag-frio","tag-gas","tag-gasto"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/3681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=3681"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/3681\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=3681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=3681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=3681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}