{"id":3627,"date":"2012-03-18T10:33:25","date_gmt":"2012-03-18T09:33:25","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=3627"},"modified":"2012-03-18T10:33:25","modified_gmt":"2012-03-18T09:33:25","slug":"16-000-euros-por-reclamaciones","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2012\/03\/18\/16-000-euros-por-reclamaciones\/","title":{"rendered":"16.000 euros por reclamaciones"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5><span style=\"color: #0000ff;\">Miranda<\/span><\/h5>\n<p><a href=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/03\/mir18-03-12blog.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3628\" title=\"mir18-03-12blog\" src=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/03\/mir18-03-12blog.jpg\" alt=\"\" width=\"600\" height=\"154\" srcset=\"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/03\/mir18-03-12blog.jpg 1031w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/03\/mir18-03-12blog-300x77.jpg 300w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/03\/mir18-03-12blog-768x197.jpg 768w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2012\/03\/mir18-03-12blog-1024x263.jpg 1024w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Las reclamaciones crecen y tambi\u00e9n los resultados. Gracias a la Oficina Municipal de Informaci\u00f3n al Consumidor (OMIC) a los mirandeses les dieron la raz\u00f3n en 98 de las quejas presentadas formalmente a lo largo de 2011 solo en el sector de telefon\u00eda. Es, un a\u00f1o m\u00e1s, el que m\u00e1s recelos y protestas ha cosechado entre la ciudadan\u00eda.<a href=\"http:\/\/www.elcorreo.com\/alava\/v\/20120318\/miranda\/euros-reclamaciones-20120318.html\" rel=\"external nofollow\"> (+)<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Miranda Las reclamaciones crecen y tambi\u00e9n los resultados. Gracias a la Oficina Municipal de Informaci\u00f3n al Consumidor (OMIC) a los mirandeses les dieron la raz\u00f3n en 98 de las quejas presentadas formalmente a lo largo de 2011 solo en el sector de telefon\u00eda. Es, un a\u00f1o m\u00e1s, el que m\u00e1s recelos y protestas ha [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[4999,5916,6735],"class_list":["post-3627","post","type-post","status-publish","format-standard","hentry","category-tiras-de-miranda","tag-omic","tag-reclamacion","tag-telefonia"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/3627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=3627"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/3627\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=3627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=3627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=3627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}