{"id":2699,"date":"2011-10-21T10:42:15","date_gmt":"2011-10-21T09:42:15","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=2699"},"modified":"2011-10-21T10:42:15","modified_gmt":"2011-10-21T09:42:15","slug":"campo-valora-la-apuesta-por-el-corredor-atlantico-una-excelente-noticia","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2011\/10\/21\/campo-valora-la-apuesta-por-el-corredor-atlantico-una-excelente-noticia\/","title":{"rendered":"Campo valora la apuesta por el Corredor Atl\u00e1ntico \u00abuna excelente noticia\u00bb"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5><span style=\"color: #0000ff;\">Miranda<\/span><\/h5>\n<p><a href=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/10\/mir21-10-11blog.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2700\" title=\"mir21-10-11blog\" src=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/10\/mir21-10-11blog.jpg\" alt=\"\" width=\"600\" height=\"151\" srcset=\"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/10\/mir21-10-11blog.jpg 1031w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/10\/mir21-10-11blog-300x76.jpg 300w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/10\/mir21-10-11blog-768x194.jpg 768w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/10\/mir21-10-11blog-1024x258.jpg 1024w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Que la Uni\u00f3n Europea haya incluido el proyecto del Corredor Ferroviario Atl\u00e1ntico entre los diez proyectos prioritarios de su red de transportes es una excelente noticia para Miranda, para sus pol\u00edgonos industriales y tambi\u00e9n para Pancorbo\u00bb, valor\u00f3 el alcalde Fernando Campo. M\u00e1xime si se tiene en cuenta que el desarrollo se plantea en \u00abunos plazos relativamente cortos para lo que son obras de estas caracter\u00edsticas\u00bb.\u00a0 <a href=\"http:\/\/www.elcorreo.com\/alava\/v\/20111021\/miranda\/campo-valora-apuesta-corredor-20111021.html\" rel=\"external nofollow\">(+)<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Miranda Que la Uni\u00f3n Europea haya incluido el proyecto del Corredor Ferroviario Atl\u00e1ntico entre los diez proyectos prioritarios de su red de transportes es una excelente noticia para Miranda, para sus pol\u00edgonos industriales y tambi\u00e9n para Pancorbo\u00bb, valor\u00f3 el alcalde Fernando Campo. M\u00e1xime si se tiene en cuenta que el desarrollo se plantea en [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[1956,3109,4905,6943],"class_list":["post-2699","post","type-post","status-publish","format-standard","hentry","category-tiras-de-miranda","tag-corredor","tag-ferroviario","tag-noticia","tag-tren"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=2699"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2699\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=2699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=2699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=2699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}