{"id":2481,"date":"2011-09-16T09:54:51","date_gmt":"2011-09-16T08:54:51","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=2481"},"modified":"2011-09-16T09:54:51","modified_gmt":"2011-09-16T08:54:51","slug":"el-parque-automovilistico-de-la-ciudad-se-aproxima-a-los-22-000-vehiculos","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2011\/09\/16\/el-parque-automovilistico-de-la-ciudad-se-aproxima-a-los-22-000-vehiculos\/","title":{"rendered":"El parque automovil\u00edstico de la ciudad se aproxima a los 22.000 veh\u00edculos"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5><span style=\"color: #0000ff;\">Miranda<\/span><\/h5>\n<p><a href=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir16-9-11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2482\" title=\"mir16-9-11\" src=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir16-9-11.jpg\" alt=\"\" width=\"602\" height=\"151\" srcset=\"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir16-9-11.jpg 2953w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir16-9-11-300x76.jpg 300w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir16-9-11-768x193.jpg 768w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir16-9-11-1024x258.jpg 1024w\" sizes=\"auto, (max-width: 602px) 100vw, 602px\" \/><\/a><\/p>\n<div><\/div>\n<div>Un coche por cada dos mirandeses, esa es pr\u00e1cticamente la media puesto que el parque automovil\u00edstico de la ciudad se sit\u00faa en 21.983 veh\u00edculos; cifra aportada ayer por la concejala Aitana Hernando a la hora de presentar las distintas actividades que van a desarrollarse durante la Semana de la Movilidad, que transcurrir\u00e1 desde hoy mismo y hasta el d\u00eda 22.\u00a0 <a href=\"http:\/\/www.elcorreo.com\/alava\/v\/20110916\/miranda\/parque-automovilistico-ciudad-aproxima-20110916.html\" rel=\"external nofollow\">(+)<\/a><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Miranda Un coche por cada dos mirandeses, esa es pr\u00e1cticamente la media puesto que el parque automovil\u00edstico de la ciudad se sit\u00faa en 21.983 veh\u00edculos; cifra aportada ayer por la concejala Aitana Hernando a la hora de presentar las distintas actividades que van a desarrollarse durante la Semana de la Movilidad, que transcurrir\u00e1 desde [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[1644,4740,5259,6574],"class_list":["post-2481","post","type-post","status-publish","format-standard","hentry","category-tiras-de-miranda","tag-coches","tag-movilidad","tag-peatones","tag-sostenible"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=2481"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2481\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=2481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=2481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=2481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}