{"id":2465,"date":"2011-09-14T12:00:44","date_gmt":"2011-09-14T11:00:44","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=2465"},"modified":"2011-09-14T12:00:44","modified_gmt":"2011-09-14T11:00:44","slug":"obama-irrumpe-en-la-crisis-y-avisa-del-riesgo-de-contagio-a-espana-e-italia","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2011\/09\/14\/obama-irrumpe-en-la-crisis-y-avisa-del-riesgo-de-contagio-a-espana-e-italia\/","title":{"rendered":"Obama irrumpe en la crisis y avisa del riesgo de contagio a Espa\u00f1a e Italia"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5><span style=\"color: #0000ff;\">Opini\u00f3n<\/span><\/h5>\n<p><a href=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/opini%C3%B3n14-9-11blog.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2466\" title=\"opini\u00f3n14-9-11blog\" src=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/opini%C3%B3n14-9-11blog.jpg\" alt=\"\" width=\"601\" height=\"225\" \/><\/a><\/p>\n<p>Obama, que ya ha exigido en otras ocasiones m\u00e1s determinaci\u00f3n a la UE, elev\u00f3 su implicaci\u00f3n en las dificultades de la eurozona durante un encuentro con medios de comunicaci\u00f3n de habla hispana. El presidente de EE UU subray\u00f3 que Grecia supone \u00abel gran problema inmediato\u00bb, pero alert\u00f3 de que la mayor amenaza para la econom\u00eda global es \u00ablo que pase en Espa\u00f1a e Italia si los mercados siguen arremetiendo contra ellos\u00bb. La ministra de Econom\u00eda, Elena Salgado, se limit\u00f3 a contestar que \u00abefectivamente\u00bb se debe evitar cualquier riesgo de contagio.\u00a0<a href=\"http:\/\/www.elcorreo.com\/alava\/v\/20110914\/economia\/obama-irrumpe-crisis-avisa-20110914.html\" rel=\"external nofollow\"> (+)<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Opini\u00f3n Obama, que ya ha exigido en otras ocasiones m\u00e1s determinaci\u00f3n a la UE, elev\u00f3 su implicaci\u00f3n en las dificultades de la eurozona durante un encuentro con medios de comunicaci\u00f3n de habla hispana. El presidente de EE UU subray\u00f3 que Grecia supone \u00abel gran problema inmediato\u00bb, pero alert\u00f3 de que la mayor amenaza para [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[2024,2956,4929,5128],"class_list":["post-2465","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-crisis","tag-europa","tag-obama","tag-panico"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=2465"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2465\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=2465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=2465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=2465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}