{"id":2442,"date":"2011-09-12T08:44:33","date_gmt":"2011-09-12T07:44:33","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=2442"},"modified":"2011-09-12T08:44:33","modified_gmt":"2011-09-12T07:44:33","slug":"ingenio-y-arte-en-las-manos","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2011\/09\/12\/ingenio-y-arte-en-las-manos\/","title":{"rendered":"Ingenio y arte en las manos"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5><span style=\"color: #0000ff\">Miranda<\/span><\/h5>\n<p><a href=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir12-9-11blog.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2443\" src=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir12-9-11blog.jpg\" alt=\"\" width=\"600\" height=\"151\" srcset=\"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir12-9-11blog.jpg 1031w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir12-9-11blog-300x76.jpg 300w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir12-9-11blog-768x194.jpg 768w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir12-9-11blog-1024x258.jpg 1024w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Dos d\u00e9cadas han pasado desde que la ciudad acogiese la primera de las ediciones de la Feria Mirandesa de Artesan\u00eda. Ayer todo el que quiso pudo observar y comprar desde trabajos de piel hasta marqueter\u00eda, cualquier tipo de obra elaborada a mano en un encuentro organizado por la Agrupaci\u00f3n Mirandesa de las Artes.\u00a0<a href=\"http:\/\/www.elcorreo.com\/alava\/v\/20110912\/miranda\/ingenio-arte-manos-20110912.html\"> (+)<br \/>\n<\/a><\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Miranda Dos d\u00e9cadas han pasado desde que la ciudad acogiese la primera de las ediciones de la Feria Mirandesa de Artesan\u00eda. Ayer todo el que quiso pudo observar y comprar desde trabajos de piel hasta marqueter\u00eda, cualquier tipo de obra elaborada a mano en un encuentro organizado por la Agrupaci\u00f3n Mirandesa de las Artes.\u00a0 [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[598,3138,3149,3662,5770],"class_list":["post-2442","post","type-post","status-publish","format-standard","hentry","category-tiras-de-miranda","tag-artesani","tag-fiesta","tag-figuras","tag-huesos","tag-publico"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=2442"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2442\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=2442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=2442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=2442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}