{"id":2423,"date":"2011-09-10T09:08:12","date_gmt":"2011-09-10T08:08:12","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=2423"},"modified":"2011-09-10T09:08:12","modified_gmt":"2011-09-10T08:08:12","slug":"nueva-york-se-blinda-ante-las-amenazas","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2011\/09\/10\/nueva-york-se-blinda-ante-las-amenazas\/","title":{"rendered":"Nueva York se blinda ante las amenazas"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5><span style=\"color: #808080\">Opini\u00f3n<\/span><\/h5>\n<p><a href=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/opini%C3%B3n10-9-11blog.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2425\" src=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/opini%C3%B3n10-9-11blog.jpg\" alt=\"\" width=\"601\" height=\"231\" \/><\/a><\/p>\n<p>La presencia policial en las calles, puentes, t\u00faneles, puertos, aeropuertos, metros, aparcamientos y edificios de Nueva York se ha ido intensificando en los \u00faltimos d\u00edas conforme se aproxima el d\u00e9cimo aniversario de los ataques del 11-S. Ayer, y tras confirmarse que se ten\u00eda la pista de una amenaza \u00abcre\u00edble aunque no corroborada\u00bb, la seguridad se increment\u00f3 y fue mucho m\u00e1s evidente en unas calles que registraban un monumental atasco dados los continuos controles policiales.<a href=\"http:\/\/www.elcorreo.com\/alava\/v\/20110910\/mundo\/nueva-york-blinda-ante-20110910.html\" rel=\"external nofollow\"> (+)<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Opini\u00f3n La presencia policial en las calles, puentes, t\u00faneles, puertos, aeropuertos, metros, aparcamientos y edificios de Nueva York se ha ido intensificando en los \u00faltimos d\u00edas conforme se aproxima el d\u00e9cimo aniversario de los ataques del 11-S. Ayer, y tras confirmarse que se ten\u00eda la pista de una amenaza \u00abcre\u00edble aunque no corroborada\u00bb, la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[31,382,971,4918,4929],"class_list":["post-2423","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-11-s-aniversario","tag-amenaza","tag-blindaje","tag-nueva-york","tag-obama"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=2423"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2423\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=2423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=2423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=2423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}